{"id":150563,"date":"2025-05-20T16:50:00","date_gmt":"2025-05-20T14:50:00","guid":{"rendered":"https:\/\/ziacom.com\/politica-de-privacidad\/"},"modified":"2026-06-19T11:31:24","modified_gmt":"2026-06-19T09:31:24","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"150563\" class=\"elementor elementor-150563 elementor-9607\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb7ab5f e-flex e-con-boxed e-con e-parent\" data-id=\"eb7ab5f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5a0491 elementor-widget elementor-widget-text-editor\" data-id=\"d5a0491\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La pr\u00e9sente Politique de confidentialit\u00e9, conform\u00e9ment \u00e0 la Loi [espagnole] 3\/2018 du 5 d\u00e9cembre et au R\u00e8glement europ\u00e9en 2016\/679 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es, recueille nos pratiques en mati\u00e8re d\u2019information et de diff\u00e9rentes options vis-\u00e0-vis de la collecte et de l\u2019utilisation de vos informations personnelles.<\/p><h2><span id=\"qui-est-le-responsable-du-traitement-de-vos-donnees\"><strong>Qui est le responsable du traitement de vos donn\u00e9es ?<\/strong><\/span><\/h2><p>Le responsable du traitement de vos donn\u00e9es personnelles est Ziacom Medical Group S.L. avec CIF [SIRET] B84115195 et sise \u00e0 Calle B\u00fahos, 2 Pinto, Madrid (Espagne).<\/p><div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper \"><table id=\"wpdtSimpleTable-174\" class=\"wpdtSimpleTable wpDataTable\" data-column=\"3\" data-rows=\"4\" data-wpid=\"174\" data-responsive=\"0\" data-has-header=\"0\"><tbody><tr class=\"wpdt-cell-row \"><td class=\"wpdt-cell wpdt-bc-C7C7C7 wpdt-tc-000000 wpdt-bold\" data-cell-id=\"A1\" data-col-index=\"0\" data-row-index=\"0\">D\u00e9nomination<\/td><td class=\"wpdt-cell wpdt-bc-C7C7C7 wpdt-tc-000000 wpdt-bold\" data-cell-id=\"B1\" data-col-index=\"1\" data-row-index=\"0\">CIF<\/td><td class=\"wpdt-cell wpdt-bc-C7C7C7 wpdt-tc-000000 wpdt-bold\" data-cell-id=\"C1\" data-col-index=\"2\" data-row-index=\"0\"><p>Site web<\/p><\/td><\/tr><tr class=\"wpdt-cell-row \"><td class=\"wpdt-cell \" data-cell-id=\"A2\" data-col-index=\"0\" data-row-index=\"1\">Ziacom Medical Group, S.L.<\/td><td class=\"wpdt-cell \" data-cell-id=\"B2\" data-col-index=\"1\" data-row-index=\"1\">B-84115195<\/td><td class=\"wpdt-cell \" data-cell-id=\"C2\" data-col-index=\"2\" data-row-index=\"1\"><a href=\"https:\/\/ziacom.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ziacom.com<\/a><\/td><\/tr><tr class=\"wpdt-cell-row \"><td class=\"wpdt-cell \" data-cell-id=\"A3\" data-col-index=\"0\" data-row-index=\"2\">Ziacor CAD-CAM, S.L.<\/td><td class=\"wpdt-cell \" data-cell-id=\"B3\" data-col-index=\"1\" data-row-index=\"2\">B-87402376<\/td><td class=\"wpdt-cell \" data-cell-id=\"C3\" data-col-index=\"2\" data-row-index=\"2\"><a href=\"https:\/\/ziacor.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ziacor.com<\/a><\/td><\/tr><tr class=\"wpdt-cell-row \"><td class=\"wpdt-cell \" data-cell-id=\"A4\" data-col-index=\"0\" data-row-index=\"3\">Biostar Laboratorios, S.L<\/td><td class=\"wpdt-cell \" data-cell-id=\"B4\" data-col-index=\"1\" data-row-index=\"3\">B-87553608<\/td><td class=\"wpdt-cell \" data-cell-id=\"C4\" data-col-index=\"2\" data-row-index=\"3\"><a href=\"https:\/\/biostar-lab.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/biostar-lab.com<\/a><\/td><\/tr><\/tbody><\/table><\/div><p>Aux fins de notre politique confidentialit\u00e9, notre courriel de contact est\u00a0:\u00a0<a href=\"mailto:info@ziacom.es\">info@ziacom.com<\/a><\/p><h2><span id=\"quel-type-de-donnees-personnelles-nous-detenons-a-votre-sujet\"><strong>Quel type de donn\u00e9es personnelles nous d\u00e9tenons \u00e0 votre sujet ?<\/strong><\/span><\/h2><p>Les renseignements collect\u00e9s concernent le produit ou le service demand\u00e9\u00a0: notamment, votre nom et coordonn\u00e9es de contact, la nature du produit ou du service demand\u00e9 et autres renseignements concern\u00e9s, afin de pouvoir vous r\u00e9pondre.<\/p><p>Parfois, Ziacom Medical Group S.L. pourrait vous inviter \u00e0 participer \u00e0 un sondage ou \u00e0 voter, notamment, pour donner un avis sur un contenu, des services ou des produits.<\/p><p>Si vous \u00eates un candidat lors d\u2019un processus de recrutement, nous disposons de votre CV, de vos renseignements fournis lors des entretiens personnels d\u2019embauche, et le cas \u00e9ch\u00e9ant, des renseignements n\u00e9cessaires \u00e0 votre embauche et au traitement des rapports professionnels.<\/p><p>En ce qui concerne tout renseignement collect\u00e9 \u00e0 travers nos sites, Ziacom Medical Group S.L. sera la responsable du traitement des donn\u00e9es.<\/p><h2><span id=\"quelle-est-la-finalite-du-traitement-de-vos-donnees-a-caractere-personnel\"><strong>Quelle est la finalit\u00e9 du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel\u00a0?<\/strong><\/span><\/h2><p>\u00c0 Ziacom Medical Group S.L. nous traitons les renseignements fournis par les parties int\u00e9ress\u00e9es pour une ou plusieurs des fins suivantes\u00a0:<\/p><ul><li>Gestion de la navigation sur le Site Internet.<\/li><li>Gestion, le cas \u00e9ch\u00e9ant, de l\u2019enregistrement de l\u2019utilisateur et identification comme utilisateur enregistr\u00e9.<\/li><li>Respect des rapports contractuels ou commerciaux en vigueur.<\/li><li>Gestion du Service de Support aux Utilisateurs.<\/li><li>Communication informative sur des produits, nouveaut\u00e9s, \u00e9v\u00e8nements, activit\u00e9s, etc. propres et du secteur.<\/li><li>Communications sur les foires et les congr\u00e8s.<\/li><li>Invitations \u00e0 des \u00e9v\u00e8nements et \u00e0 des journ\u00e9es informatives et de formation.<\/li><li>Promotion de nos produits et offres commerciales.<\/li><li>R\u00e9alisation d\u2019\u00e9tudes statistiques et de gestion de profils.<\/li><li>Enqu\u00eates et questionnaires d\u2019\u00e9valuation et de satisfaction de nos produits.<\/li><li>Toute autre fin prise en compte dans les conditions des formulaires de collecte de donn\u00e9es.<\/li><li>Respect des obligations impos\u00e9es par la l\u00e9gislation et les normes applicables.<\/li><\/ul><p>Si les fins du traitement sont de type commercial, celles-ci seront conformes aux activit\u00e9s informatives, de formation ou de promotion de produits dirig\u00e9es aux professionnels du secteur dentaire et aura pour objectif d&rsquo;am\u00e9liorer l\u2019offre de nos produits et services, et il vous sera demand\u00e9 de donner votre consentement expr\u00e8s.<\/p><p>Les activit\u00e9s aux fins informatives peuvent inclure l\u2019inscription \u00e0 une newsletter ou l\u2019assistance \u00e0 des sessions informatives ou autres. Quant aux actions de formation, elles peuvent inclure l\u2019assistance \u00e0 des sessions de formation sur des produits innovants int\u00e9ressants pour les professionnels du secteur, lesdits \u00e9v\u00e8nements pouvant \u00eatre pr\u00e9sentiels, virtuels ou r\u00e9alis\u00e9s sur un autre type de support. Quant aux promotions de produits, elles peuvent varier en fonction de la nature m\u00eame du produit, sous forme de remises par type de produit, volume d\u2019acquisition, nouveaut\u00e9, opportunit\u00e9, etc.<\/p><p>Aussi, dans le cas des candidats \u00e0 l\u2019embauche par Ziacom Medical Group S.L., la finalit\u00e9 devient le recrutement. Dans cette finalit\u00e9 est inclue la collecte du CV, son \u00e9tude, le traitement des entretiens, et le cas \u00e9ch\u00e9ant, la formalisation des rapports professionnels.<\/p><h2><span id=\"combien-de-temps-seront-conservees-vos-donnees\"><strong>Combien de temps seront conserv\u00e9es vos donn\u00e9es\u00a0?<\/strong><\/span><\/h2><p>Les donn\u00e9es personnelles fournies seront conserv\u00e9es lors d\u2019une p\u00e9riode qui ne d\u00e9passera pas le temps n\u00e9cessaire aux fins pour lequel elles ont \u00e9t\u00e9 collect\u00e9es. Par cons\u00e9quent, dans le contexte de nos rapports professionnels, vos coordonn\u00e9es seront conserv\u00e9es toujours que notre rapport contractuel soit en vigueur et\/ou jusqu\u2019\u00e0 ce que la demande de la radiation soit d\u00e9pos\u00e9e si vous ne souhaitez plus y participer.<\/p><p>Au cas o\u00f9 vous auriez choisi votre radiation, nous vous prions de bien vouloir utiliser notre lien sur le site internet de Ziacom Medical Group S.L., ou nous \u00e9crire au courriel\u00a0: info@ziacom.es. Nous vous prions de bien vouloir noter que, si vous avez d\u00e9j\u00e0 demand\u00e9 des produits ou des services au moment o\u00f9 vous avez d\u00e9cid\u00e9 de retirer votre consentement, il nous faudra peut-\u00eatre un peu de temps pour mettre \u00e0 jour vos pr\u00e9f\u00e9rences et nous assurer que nous r\u00e9pondons \u00e0 votre demande.<\/p><p>Si vous vous \u00eates inscrits dans l\u2019une de nos campagnes commerciales, vous pouvez vous d\u00e9sinscrire \u00e0 tout moment au moyen du lien de D\u00c9SINSCRIPTION qui figurera sur toutes les communications commerciales. Vous pouvez aussi vous opposer \u00e0 l&rsquo;envoi de communications commerciales au moyen du courriel\u00a0<a href=\"mailto:info@ziacom.es\">info@ziacom.com<\/a>\u00a0en sollicitant votre d\u00e9sinscription. Votre demande sera trait\u00e9e sous un d\u00e9lai d\u2019environ 72 heures, il sera donc possible que vous receviez pendant cette p\u00e9riode des communications commerciales.<\/p><p>Dans le cas des CV que nous avons re\u00e7us, nous les conserverons \u00e0 dur\u00e9e ind\u00e9termin\u00e9e, sauf indication contraire de l&rsquo;int\u00e9ress\u00e9, pour y recourir en cas de besoin de candidatures.<\/p><p>En raison du respect des obligations l\u00e9gales, il est possible que nous devions conserver vos donn\u00e9es pendant une p\u00e9riode allant au-del\u00e0 du terme des fins pour lesquelles elles ont \u00e9t\u00e9 fournies. Dans ces cas, les donn\u00e9es seront bloqu\u00e9es jusqu\u2019\u00e0 leur \u00e9limination compl\u00e8te.<\/p><h2><span id=\"quel-est-le-bien-fonde-du-traitement-de-vos-donnees\"><strong>Quel est le bien-fond\u00e9 du traitement de vos donn\u00e9es\u00a0?<\/strong><\/span><\/h2><p>La base l\u00e9gale pour le traitement de vos donn\u00e9es est celle de l&rsquo;ex\u00e9cution du contrat ou de l&rsquo;accord commercial formalis\u00e9 entre les parties. Nonobstant la l\u00e9gitimit\u00e9 d&rsquo;envoyer des mises \u00e0 jour de produits, des nouvelles du secteur, des invitations \u00e0 des \u00e9v\u00e9nements et des conf\u00e9rences et des communications sur des foires et des congr\u00e8s est bas\u00e9e sur le consentement sp\u00e9cifique, qui au moment de la collecte de vos donn\u00e9es, vous nous avez fourni, sans qu&rsquo;en aucun cas le retrait de ce consentement ne conditionne l&rsquo;ex\u00e9cution de l&rsquo;accord entre les parties.<\/p><p>Nous vous demanderons toujours, aux fins commerciales indiqu\u00e9es ci-dessus, votre consentement donn\u00e9 de fa\u00e7on libre et sans ambig\u00fcit\u00e9, qu\u2019il s\u2019agisse de campagnes dirig\u00e9es \u00e0 l\u2019information, \u00e0 la formation, \u00e0 la promotion de produits ou autres.<\/p><p>La l\u00e9gitimit\u00e9 du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel lors des processus de recrutement est fond\u00e9e sur le m\u00eame consentement donn\u00e9 de fa\u00e7on libre et sans ambig\u00fcit\u00e9 par le candidat au moment o\u00f9 il nous envoie son CV.<\/p><h2><span id=\"qui-sont-les-destinataires-de-vos-donnees-a-caractere-personnel\"><strong>Qui sont les destinataires de vos donn\u00e9es \u00e0 caract\u00e8re personnel\u00a0?<\/strong><\/span><\/h2><p>Les transferts de vos donn\u00e9es personnelles sont limit\u00e9s aux fins des relations commerciales avec Ziacom Medical Group S.L.. En cas de transfert de donn\u00e9es par nous, des contrats de charg\u00e9 de traitement sont \u00e9tablis avec des tiers non li\u00e9s \u00e0 Ziacom Medical Group S.L. impliqu\u00e9s dans lesdites t\u00e2ches. Par cons\u00e9quent, lesdits tiers s&rsquo;engagent \u00e0 respecter la confidentialit\u00e9 de vos donn\u00e9es, ainsi qu&rsquo;\u00e0 les prot\u00e9ger en suivant les mesures techniques, organisationnelles et de s\u00e9curit\u00e9 \u00e9tablies par Ziacom Medical Group S.L. .<\/p><p>Parmi ces prestataires de services se trouvent les conseils, les consultants, les commissaires aux comptes, les prestataires d\u2019entretien informatique et les prestataires de h\u00e9bergement et courriel, ainsi que les soci\u00e9t\u00e9s du groupe.<\/p><h2><span id=\"quels-sont-vos-droits-concernant-les-donnees-personnelles-fournies\"><strong>Quels sont vos droits concernant les donn\u00e9es personnelles fournies\u00a0?<\/strong><\/span><\/h2><p>Chez Ziacom Medical Group S.L. nous vous fournissons \u00e0 tout moment la confirmation de si vos donn\u00e9es personnelles sont en cours de traitement ou non. Pour ce faire, nous prenons des mesures raisonnables afin de garantir que vos donn\u00e9es personnelles soient pr\u00e9cises et mises \u00e0 jours pour la finalit\u00e9 pour laquelle elles ont \u00e9t\u00e9 collect\u00e9es. Nous vous prions de nous contacter afin de mettre \u00e0 jour ou de rectifier vos renseignements, en cas de changement, ou si vous consid\u00e9rez que nous avons collect\u00e9 une information vous concernant incorrecte.<\/p><p>Toute personne a un droit d&rsquo;acc\u00e8s \u00e0 ses donn\u00e9es \u00e0 caract\u00e8re personnel, un droit \u00e0 la portabilit\u00e9 de ses donn\u00e9es, et \u00e0 demander leur suppression, entre autres raisons, quand les donn\u00e9es ne soient plus n\u00e9cessaires aux fins pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es.<\/p><p>\u00c0 tout moment, pour des raisons concernant votre situation particuli\u00e8re, les personnes concern\u00e9es pourront s\u2019opposer au traitement de vos donn\u00e9es. Ziacom Medical Group S.L. cessera de traiter vos donn\u00e9es, sauf pour des raisons l\u00e9gitimes imp\u00e9ratives ou pour l\u2019exercice ou comme moyen de d\u00e9fense d\u2019\u00e9ventuelles r\u00e9clamations.<\/p><p>Vous pouvez exercer vos droits ou r\u00e9voquer leur consentement en vous adressant\u00a0:<\/p><ul><li>Par courriel\u00a0:<a href=\"mailto:info@ziacom.com\">\u00a0info@ziacom.com<\/a><\/li><li>Adresse Postale\u00a0: Calle B\u00fahos, 2 28320 Pinto, Madrid (Espagne)<\/li><\/ul><p>Toute demande par courrier postal ou par courriel devra \u00eatre sign\u00e9e et accompagn\u00e9e d\u2019une pi\u00e8ce d\u2019identit\u00e9 sign\u00e9e et d\u00e9taillant l&rsquo;adresse o\u00f9 vous souhaitez que la r\u00e9ponse soit envoy\u00e9e. Vous recevrez une r\u00e9ponse dans un d\u00e9lai d\u2019un \u00e0 trois mois suite \u00e0 la r\u00e9ception de votre demande. \/span&gt;<\/p><p>Finalement, nous vous informons que si nous ne r\u00e9pondons pas dans les d\u00e9lais \u00e0 l\u2019une de vos demandes ou si vous n\u2019\u00eates pas d&rsquo;accord avec notre r\u00e9ponse, vous pouvez vous adresser \u00e0 l\u2019Agencia Espa\u00f1ola de Protecci\u00f3n de Datos [Agence espagnole \u00e0 la Protection des donn\u00e9es], ainsi que pour exercer la tutelle de vos droits.<\/p><h2><span id=\"protection-de-vos-informations\"><strong>Protection de vos informations<\/strong><\/span><\/h2><p>Conform\u00e9ment aux lois et aux conditions requises applicables, Ziacom Medical Group S.L. met en marche des protections physiques, \u00e9lectroniques et administratives pour sauvegarder vos informations personnelles d\u2019une \u00e9ventuelle perte, mauvaise utilisation, modification, vol, acc\u00e8s non autoris\u00e9 ou r\u00e9v\u00e9lation non autoris\u00e9e. Nous v\u00e9rifions ces protections r\u00e9guli\u00e8rement afin de minimiser les risques pos\u00e9s par les nouvelles menaces, aussit\u00f4t nous avons connaissance de leur existence. Cependant, comme il s&rsquo;av\u00e8re pour tous les sites Internet, nous ne sommes malheureusement pas en mesure de garantir \u00e0 100\u00a0% la s\u00e9curit\u00e9 des donn\u00e9es que nous collectons via nos sites Internet publics.<\/p><p>Si vous nous fournissez tout renseignement personnel confidentiel \u00e0 travers notre site Internet, tels que les donn\u00e9es de votre carte de cr\u00e9dit (aux fins de facturation), nous vous prions de bien vouloir le faire depuis un ordinateur avec un logiciel anti-virus mis \u00e0 jour, afin de minimiser le risque d\u2019acc\u00e8s \u00e0 vos donn\u00e9es personnelles avant que cette derni\u00e8re n\u2019arrive \u00e0 nous. Pour les paiements par carte de cr\u00e9dit effectu\u00e9s sur ce site, vous serez redirig\u00e9 vers un autre site qui a \u00e9t\u00e9 v\u00e9rifi\u00e9 pour se conformer \u00e0 une s\u00e9rie d&rsquo;exigences de s\u00e9curit\u00e9 sp\u00e9cifiques pour la collecte et le traitement des donn\u00e9es de carte de cr\u00e9dit, d&rsquo;apr\u00e8s le Payment Card Industry (organisation des principales soci\u00e9t\u00e9s mondiales de cartes de cr\u00e9dit).<\/p><h2><span id=\"notre-engagement-avec-la-confidentialite-sur-les-mineurs\"><strong>Notre engagement avec la confidentialit\u00e9 sur les mineurs<\/strong><\/span><\/h2><p>Le site Internet Ziacom Medical Group S.L. ne s&rsquo;adresse en aucun cas \u00e0 des enfants de moins de 13 ans. Toute information personnelle collect\u00e9e involontairement sur un mineur sera imm\u00e9diatement \u00e9limin\u00e9e. Ceci ne concerne pas les renseignements m\u00e9dicaux sur les enfants susceptibles d\u2019\u00eatre fournis par les praticiens concernant une demande de renseignements sur un produit ou un service. Les utilisateurs de moins de 18 ans doivent envoyer des renseignements personnels de ses repr\u00e9sentants l\u00e9gaux (notamment, de leurs parents), avec lesquels nous contacterons afin de confirmer que l\u2019utilisation du site Internet se fait avec le consentement d\u2019un adulte.<\/p><h2><span id=\"changements-dans-cette-politique-de-confidentialite\"><strong>Changements dans cette politique de confidentialit\u00e9<\/strong><\/span><\/h2><p>Dans la mesure o\u00f9 nous fournissons d\u2019autres services et comme cons\u00e9quence de l\u2019\u00e9volution des lois et r\u00e9glementations, il s\u2019av\u00e8rerait n\u00e9cessaire de r\u00e9viser ou de mettre \u00e0 jour la pr\u00e9sente Politique de confidentialit\u00e9. Nous vous conseillons de r\u00e9viser la pr\u00e9sente Politique de confidentialit\u00e9 une fois disponible sur notre site Internet\u00a0<a href=\"https:\/\/ziacom.com\/fr\/\">\u00a0www.ziacom.com\u00a0<\/a>\u00a0afin d\u2019\u00eatre \u00e0 jour sur les \u00e9ventuels changements. Veuillez consid\u00e9rer que l\u2019utilisation des renseignements personnels se fait conform\u00e9ment \u00e0 la Politique de confidentialit\u00e9 en vigueur au moment o\u00f9 vos renseignements ont \u00e9t\u00e9 collect\u00e9s.<\/p><h2><span id=\"liens-vers-des-sites-internet-tiers\"><strong>Liens vers des sites Internet tiers<\/strong><\/span><\/h2><p>Notre site Internet peut contenir des liens vers d&rsquo;autres sites Internet, dont la propri\u00e9t\u00e9 ou la gestion ne correspond pas \u00e0 Ziacom Medical Group S.L. Vous devez examiner attentivement les politiques et pratiques de confidentialit\u00e9 de ces autres sites Internet, car nous n&rsquo;avons aucun contr\u00f4le ni responsabilit\u00e9 sur les pratiques ou les politiques des sites Internet tiers qui ne nous appartiennent pas.<\/p><h2><span id=\"cookies-et-autres-outils-de-suivi-sur-internet\"><strong>Cookies et autres outils de suivi sur Internet<\/strong><\/span><\/h2><p>Comme plusieurs sites Internet, nous utilisons des cookies afin d\u2019am\u00e9liorer le service que nous vous proposons. Un cookie est un petit fichier de texte envoy\u00e9 par un autre site Internet vers votre navigateur et qui est d\u00e9pos\u00e9 sur le disque dur de votre ordinateur. Les renseignements collect\u00e9s par les cookies nous permettent savoir si vous avez d\u00e9j\u00e0 visit\u00e9 le site pr\u00e9alablement et ils vous aident \u00e0 ne pas r\u00e9introduire vos renseignements \u00e0 chaque visite. Afin que les cookies puissent fonctionner, vous devez donner votre consentement pour visiter notre site Internet, sauf pour les cookies n\u00e9cessaires au fonctionnement du site Internet. Aussi, vous pouvez configurer votre navigateur afin de refuser tous les cookies de ce site et de tout autre susceptible d\u2019\u00eatre visit\u00e9. Ceci vous conf\u00e8re plus de contr\u00f4le sur l&rsquo;acceptation de cookies sur votre ordinateur, mais certaines rubriques du site internet sont susceptibles de ne pas fonctionner correctement ou de le faire plus lentement si vous d\u00e9cidez de refuser les cookies. Pour plus de renseignements, vous pouvez consulter sur notre site internet notre\u00a0<a href=\"https:\/\/ziacom.com\/fr\/avis-de-cookies\/\">politique de cookies.<\/a><\/p><h2><span id=\"utilisation-et-echanges-des-informations-collectees\"><strong>Utilisation et \u00e9changes des informations collect\u00e9es<\/strong><\/span><\/h2><p>Ziacom Medical Group S.L. se r\u00e9serve le droit de partager vos informations avec ses soci\u00e9t\u00e9s filiales, subsidiaires et autres soci\u00e9t\u00e9s li\u00e9es, ainsi qu&rsquo;avec des tiers qui collaborent avec nous dans la provision de produits ou la prestation de services que vous demandez ou dans l&rsquo;am\u00e9lioration de notre publicit\u00e9 ou de notre gestion. Cela inclut les entreprises qui nous fournissent des analyses sur l&rsquo;utilisation de notre site Internet afin que nous puissions \u00e9valuer cette utilisation et continuer \u00e0 am\u00e9liorer notre contenu web.<\/p><p>Au cas o\u00f9 vos donn\u00e9es soient transf\u00e9r\u00e9es hors du pays o\u00f9 vous habitez, notamment, vers Ziacom Medical Group S.L. sise dans un autre pays, diff\u00e9rentes r\u00e9glementations \u00e0 l&rsquo;utilisation et \u00e0 la protection de vos donn\u00e9es seraient applicables. Ziacom Medical Group S.L. a mis en place toutes les mesures n\u00e9cessaires afin de garantir que vos donn\u00e9es sont d\u00fbment prot\u00e9g\u00e9es, quel que soit le pays. Cela comprend l&rsquo;obtention de garanties \u00e9crites de la part de tout tiers ayant acc\u00e8s \u00e0 vos donn\u00e9es dans le but de l\u2019exiger \u00e0 adopter les r\u00e9glementations pertinentes afin de garantir un niveau de protection de vos donn\u00e9es \u00e9quivalent \u00e0 celui adopt\u00e9 par Ziacom Medical Group S.L.<\/p><p>Ziacom Medical Group S.L. ne partage ni ne vend les informations personnelles que vous nous fournissez via notre site Internet pour une utilisation ind\u00e9pendante par un tiers.<\/p><p>Ponctuellement, nous fournirons des statistiques globales sur les clients, les ventes, les mod\u00e8les de trafic en ligne et des informations connexes \u00e0 des tiers de confiance pour nous aider \u00e0 am\u00e9liorer nos activit\u00e9s et nos services\u00a0; cependant, ces donn\u00e9es statistiques n&rsquo;incluent aucune information personnellement identifiable.<\/p><p>Au cas o\u00f9 nous vendrions, c\u00e9derions ou transf\u00e9rions tout ou une partie de l&rsquo;activit\u00e9 de Ziacom Medical Group S.L., nous pouvons \u00e9galement c\u00e9der vos informations personnelles \u00e0 l&rsquo;acheteur. Cependant, l&rsquo;acqu\u00e9reur, le cessionnaire ou le destinataire d&rsquo;une telle cession sera tenu de prot\u00e9ger vos informations personnelles d&rsquo;une mani\u00e8re conforme aux exigences de la pr\u00e9sente politique de confidentialit\u00e9.<\/p><h2><span id=\"transferts-internationaux-de-donnees\"><strong>Transferts internationaux de donn\u00e9es<\/strong><\/span><\/h2><p>Si vos donn\u00e9es sont transf\u00e9r\u00e9es vers des pays hors de l\u2019espace \u00e9conomique europ\u00e9en ou non assimil\u00e9s par l\u2019Union Europ\u00e9enne par rapport au respect de la confidentialit\u00e9 de mani\u00e8re assimilable \u00e0 la r\u00e9glementation europ\u00e9enne, notamment, vers Ziacom Medical Group S.L. sise dans d\u2019autres pays, diff\u00e9rentes r\u00e9glementations \u00e0 l&rsquo;utilisation et \u00e0 la protection de vos donn\u00e9es seraient applicables.<\/p><p>Ziacom Medical Group S.L. a mis en place toutes les mesures n\u00e9cessaires afin de garantir que vos donn\u00e9es soient d\u00fbment prot\u00e9g\u00e9es, quel que soit le pays o\u00f9 celles-ci seront trait\u00e9es. Cela comprend l&rsquo;obtention de garanties \u00e9crites de la part de tout tiers ayant acc\u00e8s \u00e0 vos donn\u00e9es dans le but de l\u2019exiger \u00e0 adopter les r\u00e9glementations pertinentes afin de garantir un niveau de protection de vos donn\u00e9es \u00e9quivalent \u00e0 celui adopt\u00e9 par Ziacom Medical Group S.L.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La pr\u00e9sente Politique de confidentialit\u00e9, conform\u00e9ment \u00e0 la Loi [espagnole] 3\/2018 du 5 d\u00e9cembre et au R\u00e8glement europ\u00e9en 2016\/679 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-150563","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Ziacom\" \/>\n<meta property=\"og:description\" content=\"La pr\u00e9sente Politique de confidentialit\u00e9, conform\u00e9ment \u00e0 la Loi [espagnole] 3\/2018 du 5 d\u00e9cembre et au R\u00e8glement europ\u00e9en 2016\/679 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T09:31:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-05-20T14:50:00+00:00\",\"dateModified\":\"2026-06-19T09:31:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - Ziacom","og_description":"La pr\u00e9sente Politique de confidentialit\u00e9, conform\u00e9ment \u00e0 la Loi [espagnole] 3\/2018 du 5 d\u00e9cembre et au R\u00e8glement europ\u00e9en 2016\/679 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement [&hellip;]","og_url":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/","og_site_name":"Ziacom","article_modified_time":"2026-06-19T09:31:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/","url":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/fr\/#website"},"datePublished":"2025-05-20T14:50:00+00:00","dateModified":"2026-06-19T09:31:24+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/fr\/#website","url":"https:\/\/ziacom.com\/fr\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/150563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/comments?post=150563"}],"version-history":[{"count":7,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/150563\/revisions"}],"predecessor-version":[{"id":154260,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/150563\/revisions\/154260"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/media?parent=150563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}