{"id":151413,"date":"2026-03-26T12:15:13","date_gmt":"2026-03-26T11:15:13","guid":{"rendered":"https:\/\/ziacom.com\/ifus\/"},"modified":"2026-07-01T16:10:49","modified_gmt":"2026-07-01T14:10:49","slug":"ifus","status":"publish","type":"page","link":"https:\/\/ziacom.com\/fr\/ifus\/","title":{"rendered":"Ifus"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"151413\" class=\"elementor elementor-151413 elementor-134044\" data-elementor-post-type=\"page\">\n\t\t\t\t<section class=\"elementor-element elementor-element-b4a1514 header-intro  e-flex e-con-boxed e-con e-parent\" data-id=\"b4a1514\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a539eb7 title elementor-widget elementor-widget-heading\" data-id=\"a539eb7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Mode d'emploi<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7851cc subtitle elementor-widget elementor-widget-heading\" data-id=\"e7851cc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous pouvez consulter ou t\u00e9l\u00e9charger nos fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e87733d padding-section e-flex e-con-boxed e-con e-parent\" data-id=\"e87733d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d9d0549 e-con-full ifus-bg e-flex e-con e-child\" data-id=\"d9d0549\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79a8c82 elementor-widget elementor-widget-heading\" data-id=\"79a8c82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instructions de recherche dans le mode d'emploi :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5d830d elementor-widget elementor-widget-text-editor\" data-id=\"c5d830d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>En fonction du syst\u00e8me d&rsquo;implant ou du syst\u00e8me de transport inclus avec le produit, vous pouvez rechercher le mode d&#8217;emploi correspondant dans le menu ci-dessous.<\/li><li>S\u00e9lectionnez le produit : le document s&rsquo;ouvrira alors dans une nouvelle page.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de49ac elementor-widget elementor-widget-heading\" data-id=\"1de49ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IFUS EN VIGUEUR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37ec551 elementor-widget elementor-widget-shortcode\" data-id=\"37ec551\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ifus-accordion-wrapper\"><div class=\"ifus-accordion-search-wrap\"><input id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-search\" type=\"search\" class=\"ifus-accordion-search\" placeholder=\"Buscar IFUs\" aria-label=\"Buscar en acordeon IFUs\"><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845\" class=\"elementor-accordion\" role=\"tablist\" data-items-per-page=\"5\"><div class=\"elementor-accordion-item\" data-item-index=\"0\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-0\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-0\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants Ziacom<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-0\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-0\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-113\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"1\"\n           data-wpID=\"113\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Juin 2026                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<div><p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/IFUS\/IFU-Sistema-de-implantes-Ziacom-v00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-113'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"1\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-1\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-1\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM8N y ZM8\u00aeS No Mount (I-Drive) avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-1\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-1\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-74\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"5\"\n           data-wpID=\"74\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-12                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<div><p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v12.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre \n2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-11                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<div><p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v11.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"htps:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-74'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"2\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-2\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-2\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Accessoires \/ Instruments<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-2\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-2\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-75\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"7\"\n           data-wpID=\"75\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Janvier 2026                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-02                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-02.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-14.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-13                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-13.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juillet 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-08                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-08.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A6\"\n                    data-col-index=\"0\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre  2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B6\"\n                    data-col-index=\"1\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C6\"\n                    data-col-index=\"2\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A7\"\n                    data-col-index=\"0\"\n                    data-row-index=\"6\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B7\"\n                    data-col-index=\"1\"\n                    data-row-index=\"6\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C7\"\n                    data-col-index=\"2\"\n                    data-row-index=\"6\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Aditamentos-e-instrumental\/IFU-Aditamentos-Instrumental-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-75'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"3\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-3\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-3\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Implants orthodontiques DSQ<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-3\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-3\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-78\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"6\"\n           data-wpID=\"78\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-11                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-11.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre  2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-10                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-10.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-03                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-03.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Novembre 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-02                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-02.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A6\"\n                    data-col-index=\"0\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B6\"\n                    data-col-index=\"1\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C6\"\n                    data-col-index=\"2\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-de-ortodoncia-DSQ\/IFU-Implantes-de-ortodoncia-DSQ-Rev-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-78'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"4\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-4\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-4\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Vis Di\u00b2gital Arch 1.0<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-4\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-4\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-89\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"2\"\n           data-wpID=\"89\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"Septiembre 2025\trev-01\tDescargar\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mars 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-de-impresi&oacute;n-digital-Di2gital-Arch-10\/IFU-Di2gital-Arch-1.0-Tornillo-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-89'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"5\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-5\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-5\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Microimplant Di\u00b2gital Arch 2.0<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-5\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-5\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-90\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"2\"\n           data-wpID=\"90\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-de-impresi%C3%B3n-digital-Di2gital-Arch-20\/IFU-Di2gital-Arch-2.0-Microimplante-Rev-07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mars 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-de-impresi&oacute;n-digital-Di2gital-Arch-20\/IFU-Di2gital-Arch-2.0-Microimplante-Rev-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-90'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"6\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-6\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-6\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Pins de fixation Ziasure ZS1<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-6\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-6\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-114\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"114\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Pines-de-fijaci%C3%B3n-Ziasure-ZS1\/IFU-Pines-de-fijacion-Ziacom-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Pines-de-fijaci&oacute;n-Ziasure-ZS1\/IFU-Pines-de-fijacion-Ziacom-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Avril 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Pines-de-fijaci&oacute;n-Ziasure-ZS1\/IFU-Pines-de-fijacion-Ziacom-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-114'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"7\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-7\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-7\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Vis de fixation Ziasure ZS2<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-7\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-7\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-116\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"116\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Tornillos-de-fijaci%C3%B3n-Ziasure-ZS2\/IFU-Tornillos-de-fijacion-Ziacom-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Tornillos-de-fijaci&oacute;n-Ziasure-ZS2\/IFU-Tornillos-de-fijacion-Ziacom-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Avril 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Tornillos-de-fijaci&oacute;n-Ziasure-ZS2\/IFU-Tornillos-de-fijacion-Ziacom-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-116'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"8\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-8\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-8\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Feuilles Ziasure ZS3<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-8\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-8\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-115\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"2\"\n           data-wpID=\"115\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Laminas-ziasure-ZS3\/IFU-Ziasure-Laminas-ZS3-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-03                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Laminas-ziasure-ZS3\/IFU-Ziasure-Laminas-ZS3-Rev-03.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-115'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"9\"><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-9\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"tab\" aria-controls=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-9\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Implant Card Ziacom<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-content-9\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-tab-9\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-117\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"1\"\n           data-wpID=\"117\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Juin 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implant-Card-Ziacom\/Implant-Card-Ziacom.pdf\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-117'>\n<\/style>\n<\/div><\/div><div class=\"ifus-accordion-pagination\" data-total-pages=\"2\"><div class=\"ifus-page-btn ifus-page-prev controls is-disabled\" aria-disabled=\"true\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/prev.svg\" alt=\"Anterior\"><\/div><button type=\"button\" class=\"ifus-page-number controls is-active\" data-page=\"1\">1<\/button><button type=\"button\" class=\"ifus-page-number controls\" data-page=\"2\">2<\/button><div class=\"ifus-page-btn ifus-page-next controls\" aria-disabled=\"false\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/next.svg\" alt=\"Siguiente\"><\/div><\/div><\/div><div class=\"ifus-accordion-empty\" style=\"display:none;\">No se han encontrado resultados.<\/div><\/div><script>(function(){var root=document.getElementById(\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845\");var searchInput=document.getElementById(\"ifus-accordion-c4e03ae8-ea8d-4c46-9f19-53a3a09a6845-search\");if(!root){return;}var prevIconSrc=\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/themes\\\/hello-elementor-child\\\/assets\\\/images\\\/acordeon\\\/prev.svg\";var nextIconSrc=\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/themes\\\/hello-elementor-child\\\/assets\\\/images\\\/acordeon\\\/next.svg\";var titles=Array.prototype.slice.call(root.querySelectorAll(\".elementor-tab-title\"));var items=Array.prototype.slice.call(root.querySelectorAll(\".elementor-accordion-item\"));var perPage=parseInt(root.getAttribute(\"data-items-per-page\"),10)||4;var currentPage=1;var filteredItems=items.slice();var totalPages=Math.max(1,Math.ceil(filteredItems.length\/perPage));var pagination=root.querySelector(\".ifus-accordion-pagination\");var wrapper=root.closest(\".ifus-accordion-wrapper\");var emptyState=wrapper?wrapper.querySelector(\".ifus-accordion-empty\"):null;var activeFilterTerm=\"\";function setIconState(title,isOpen){if(!title){return;}var closedIcon=title.querySelector(\".ifus-accordion-icon-closed\");var openIcon=title.querySelector(\".ifus-accordion-icon-open\");if(closedIcon){closedIcon.style.display=isOpen?\"none\":\"inline-block\";}if(openIcon){openIcon.style.display=isOpen?\"inline-block\":\"none\";}}function closeTitle(title){title.classList.remove(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"false\");setIconState(title,false);var panel=title.nextElementSibling;if(panel){panel.classList.remove(\"elementor-active\");panel.style.display=\"none\";}}function openTitle(title){if(!title){return;}title.classList.add(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"true\");setIconState(title,true);var panel=title.nextElementSibling;if(panel){panel.classList.add(\"elementor-active\");panel.style.display=\"block\";}}function closeAllTitles(){titles.forEach(function(title){closeTitle(title);});}function isItemVisible(item){return item.style.display!==\"none\";}function normalize(text){return (text||\"\").toLowerCase();}function escapeRegExp(text){return text.replace(\/[.*+?^${}()|[\\]\\\\]\/g,\"\\$&\");}function escapeHtml(text){return text.replace(\/&\/g,\"&amp;\").replace(\/<\/g,\"&lt;\").replace(\/>\/g,\"&gt;\").replace(\/\\\"\/g,\"&quot;\").replace(\/\\x27\/g,\"&#39;\");}function setTitleHighlight(item,term){var titleEl=item.querySelector(\".ifus-accordion-title-text\");if(!titleEl){return;}var original=titleEl.getAttribute(\"data-original-title\");if(!original){original=titleEl.textContent||\"\";titleEl.setAttribute(\"data-original-title\",original);}if(!term){titleEl.textContent=original;return;}var safeText=escapeHtml(original);var regex=new RegExp(\"(\"+escapeRegExp(term)+\")\",\"ig\");titleEl.innerHTML=safeText.replace(regex,\"<u>$1<\/u>\");}function createArrowControl(type){var isPrev=type===\"prev\";var div=document.createElement(\"div\");div.className=\"ifus-page-btn ifus-page-\"+type+\" controls\";div.setAttribute(\"role\",\"button\");div.setAttribute(\"tabindex\",\"0\");var disabled=isPrev?currentPage<=1:currentPage>=totalPages;if(disabled){div.classList.add(\"is-disabled\");div.setAttribute(\"aria-disabled\",\"true\");}else{div.setAttribute(\"aria-disabled\",\"false\");}var img=document.createElement(\"img\");img.src=isPrev?prevIconSrc:nextIconSrc;img.alt=isPrev?\"Anterior\":\"Siguiente\";div.appendChild(img);div.addEventListener(\"click\",function(){if(isPrev&&currentPage>1){closeAllTitles();renderPage(currentPage-1);}if(!isPrev&&currentPage<totalPages){closeAllTitles();renderPage(currentPage+1);}});div.addEventListener(\"keydown\",function(e){if(e.key===\"Enter\"||e.key===\" \"){e.preventDefault();div.click();}});return div;}function renderPaginationButtons(){if(!pagination){return;}pagination.innerHTML=\"\";if(totalPages<=1){pagination.style.display=\"none\";return;}pagination.style.display=\"flex\";pagination.appendChild(createArrowControl(\"prev\"));for(var page=1;page<=totalPages;page++){var btn=document.createElement(\"button\");btn.type=\"button\";btn.className=\"ifus-page-number controls\"+(page===currentPage?\" is-active\":\"\");btn.setAttribute(\"data-page\",String(page));btn.textContent=String(page);btn.addEventListener(\"click\",function(e){var target=e.currentTarget;var pageValue=parseInt(target.getAttribute(\"data-page\"),10);if(!isNaN(pageValue)){closeAllTitles();renderPage(pageValue);}});pagination.appendChild(btn);}pagination.appendChild(createArrowControl(\"next\"));}function renderPage(page){currentPage=Math.min(Math.max(page,1),totalPages);var start=(currentPage-1)*perPage;var end=start+perPage;var pageItems=filteredItems.slice(start,end);items.forEach(function(item){item.style.display=\"none\";});pageItems.forEach(function(item){item.style.display=\"block\";if(activeFilterTerm){var title=item.querySelector(\".elementor-tab-title\");openTitle(title);}});if(emptyState){emptyState.style.display=filteredItems.length?\"none\":\"block\";}renderPaginationButtons();}function renderFilteredOpenAll(){items.forEach(function(item){item.style.display=\"none\";});filteredItems.forEach(function(item){item.style.display=\"block\";var title=item.querySelector(\".elementor-tab-title\");openTitle(title);});if(emptyState){emptyState.style.display=filteredItems.length?\"none\":\"block\";}renderPaginationButtons();}function applyFilter(){var term=normalize(searchInput?searchInput.value:\"\").trim();activeFilterTerm=term;filteredItems=items.filter(function(item){var titleTextEl=item.querySelector(\".ifus-accordion-title-text\");var originalText=titleTextEl?(titleTextEl.getAttribute(\"data-original-title\")||titleTextEl.textContent||\"\"):\"\";setTitleHighlight(item,term);return normalize(originalText).indexOf(term)!==-1;});totalPages=Math.max(1,Math.ceil(filteredItems.length\/perPage));closeAllTitles();renderPage(1);}titles.forEach(function(title){setIconState(title,false);title.addEventListener(\"click\",function(e){e.preventDefault();var parentItem=title.closest(\".elementor-accordion-item\");if(parentItem&&!isItemVisible(parentItem)){return;}var current=title.nextElementSibling;var isOpen=title.classList.contains(\"elementor-active\");closeAllTitles();if(!isOpen){title.classList.add(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"true\");setIconState(title,true);if(current){current.classList.add(\"elementor-active\");current.style.display=\"block\";}}});});if(searchInput){searchInput.addEventListener(\"input\",applyFilter);}renderPage(1);})();<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1764b4a e-con-full ifus-bg e-flex e-con e-child\" data-id=\"1764b4a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-baa1b74 elementor-widget elementor-widget-heading\" data-id=\"baa1b74\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IFUS PR\u00c9C\u00c9DENTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5e833 elementor-widget elementor-widget-shortcode\" data-id=\"3a5e833\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ifus-accordion-wrapper\"><div class=\"ifus-accordion-search-wrap\"><input id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-search\" type=\"search\" class=\"ifus-accordion-search\" placeholder=\"Buscar IFUs\" aria-label=\"Buscar en acordeon IFUs\"><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032\" class=\"elementor-accordion\" role=\"tablist\" data-items-per-page=\"5\"><div class=\"elementor-accordion-item\" data-item-index=\"0\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-0\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-0\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM8N y ZM8\u00aeS No Mount (I-Drive) avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-0\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-0\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-74\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"5\"\n           data-wpID=\"74\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-12                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<div><p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v12.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre \n2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-11                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<div><p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v11.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"htps:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-74'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"1\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-1\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-1\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZMK y ZMR avec transporteur en plastique avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-1\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-1\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-76\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"5\"\n           data-wpID=\"76\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-09                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZMK-y-ZMR-con-aplicador-y-superficie-Titansure\/IFU-Implante-transportador-ZMK-ZMR-Rev-09.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-08                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZMK-y-ZMR-con-aplicador-y-superficie-Titansure\/IFU-Implante-transportador-ZMK-ZMR-Rev-08.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZM8N-y-ZM8S\/IFU-Implantes-ZM8-v05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-76'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"2\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-2\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-2\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM4, ZM4MT, ZM1, Zinic, ZinicMT et ZinicSHORTY Mount Z2Plus avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-2\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-2\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-77\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"77\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-Z2Plus-con-superficie-Titansure\/IFU-Implante-Mount-Z2Plus-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-Z2Plus-con-superficie-Titansure\/IFU-Implante-Mount-Z2Plus-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-03                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-Z2Plus-con-superficie-Titansure\/IFU-Implante-Mount-Z2Plus-Rev-03.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-77'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"3\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-3\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-3\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants Zinic y ZM4 Mount 3DPlus avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-3\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-3\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-79\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"79\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Mai  2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-3DPlus-con-superficie-Titansure\/IFU-Implante-Mount-3DPlus-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-3DPlus-con-superficie-Titansure\/IFU-Implante-Mount-3DPlus-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-03                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-3DPlus-con-superficie-Titansure\/IFU-Implante-Mount-3DPlus-Rev-03.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-79'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"4\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-4\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-4\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM1, ZM4MT, Zinic\u00aeMT et Zinic\u00aeMTX Mount ZPlus avec surface Titansure Active.<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-4\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-4\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-80\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"80\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-1                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-ZPlus-Titansure-Active\/IFU-Ziacom-ZPlus-Titansure-Active-Rev-Q-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-ZPlus-Titansure-Active\/IFU-Ziacom-ZPlus-Titansure-Active-Rev-14.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-13                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistema-ZPlus-Titansure-Active\/IFU-Ziacom-ZPlus-Titansure-Active-Rev-13.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-80'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"5\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-5\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-5\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM4, ZM4MT, ZM1, Zinic et ZinicMT Mount ZPlus avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-5\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-5\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-81\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"4\"\n           data-wpID=\"81\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-09                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-09.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-08                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-08.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Novembre 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-81'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"6\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-6\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-6\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants ZM4, ZM4MT, ZM1, Zinic\u00ae, Zinic\u00aeSX, Zinic\u00aeMT et Zinic\u00aeMTX avec fixation ZPlus<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-6\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-6\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-82\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"82\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-1                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-Q-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-14.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-13                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-Mount-ZPlus-con-superficie-Titansure\/IFU-Implante-transportador-ZPlus-Rev-13.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-82'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"7\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-7\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-7\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants GALAXY, ZV2 et ZM10 No Mount V-Press avec surface Titansure<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-7\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-7\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-83\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"6\"\n           data-wpID=\"83\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-1                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure\/IFU-Implante-VPres-Rev-Q01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-11                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure\/IFU-Implante-VPres-Rev-11.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-10                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A6\"\n                    data-col-index=\"0\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B6\"\n                    data-col-index=\"1\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C6\"\n                    data-col-index=\"2\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure\/IFU-Implante-VPres-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-83'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"8\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-8\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-8\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants GALAXY, ZV2 et ZM10 No Mount V-Press avec surface Titansure Active<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-8\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-8\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-84\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"5\"\n           data-wpID=\"84\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-Q-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-GALAXY-y-ZV2-con-superficie-Titansure-Active\/IFU-Implantes-VPress-Titansure-Active-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-84'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"9\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-9\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-9\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants Zinic\u00ae, Zinic\u00aeSX, Zinic\u00aeMT et Zinic\u00ae MTX sans montage avec surface Titansure.<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-9\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-9\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-85\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"6\"\n           data-wpID=\"85\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-1                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-Q-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-10                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-09.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-09                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-09.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-05                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-05.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-04                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-04.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A6\"\n                    data-col-index=\"0\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Mai 2020                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B6\"\n                    data-col-index=\"1\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-03                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C6\"\n                    data-col-index=\"2\"\n                    data-row-index=\"5\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Implantes-No-Mount\/IFU-Implantes-No-Mount-Rev-03.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-85'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"10\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-10\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-10\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes d\u2019implants Zinic, Zinic MT et Zinic Shorty No Mount avec surface Titansure Active<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-10\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-10\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-86\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"2\"\n           data-wpID=\"86\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Mai 2022                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZINIC-No-Mount-con-superficie-Titansure-Active\/IFU-Implantes-No-Mount-Titansure-Active-Rev-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Juin 2021                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-00                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); padding: 10px; margin-left: 100px; margin-right: 100px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZINIC-No-Mount-con-superficie-Titansure-Active\/IFU-Implantes-No-Mount-Titansure-Active-Rev-00.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-86'>\n<\/style>\n<\/div><\/div><div class=\"elementor-accordion-item\" data-item-index=\"11\"><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-11\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"tab\" aria-controls=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-11\" aria-expanded=\"false\"><a class=\"elementor-accordion-title\" href=\"#\"><div class=\"flex-wrap\"><div class=\"ifus-accordion-icon-wrap\" aria-hidden=\"true\"><div class=\"ifus-accordion-icon ifus-accordion-icon-closed\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/plus.svg\" alt=\"Closed Icon\"><\/div><\/div><div class=\"ifus-accordion-icon ifus-accordion-icon-open\" style=\"display:none;\"><div class=\"flex-wrap-icon\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/menos.svg\" alt=\"Open Icon\"><\/div><\/div><\/div><div class=\"ifus-accordion-title-text\">Syst\u00e8mes implantaires Zinic\u00ae, Zinic\u00aeSX, Zinic\u00aeMT et Zinic\u00aeMTX No Mount avec surface Titansure Active<\/div><\/div><\/a><\/div><div id=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-content-11\" class=\"elementor-tab-content elementor-clear fix\" data-tab=\"12\" role=\"tabpanel\" aria-labelledby=\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-tab-11\" style=\"display:none;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n\"\n    >\n        <table id=\"wpdtSimpleTable-87\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"3\"\n           data-rows=\"3\"\n           data-wpID=\"87\"\n           data-responsive=\"0\"\n           data-has-header=\"0\">\n\n                    <tbody>        <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        rev-01                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:33.333333333333%;                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZINIC-No-Mount-con-superficie-Titansure-Active\/IFU-Implantes-No-Mount-Titansure-Active-Rev-Q-01.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2025                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-07                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZINIC-No-Mount-con-superficie-Titansure-Active\/IFU-Implantes-No-Mount-Titansure-Active-Rev-07.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row \" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        Septembre 2024                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        rev-06                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        <div data-type-content=\"wpdt-html-content\">\n<p style=\"text-align: center; margin-top: 25px;\"><a class=\"wptb-button wptb-plugin-button-order-left\" style=\"position: relative; border-radius: 5px; background-color: #00365f; color: #ffffff; justify-content: center; transform: scale(1); margin-left: 100px; margin-right: 100px; padding: 10px;\" href=\"https:\/\/ziacom.com\/ifus-version\/Sistemas-de-implantes-ZINIC-No-Mount-con-superficie-Titansure-Active\/IFU-Implantes-No-Mount-Titansure-Active-Rev-06.pdf\" target=\"_blank\" rel=\"noopener\" data-wptb-element-bg-color=\"#00365FFF\" data-wptb-element-color=\"#FFFFFF\" data-wptb-element-hover-bg-color=\"#BEBEBEFF\" data-wptb-element-hover-text-color=\"#FFFFFFFF\" data-wptb-element-hover-scale=\"1\">T\u00e9l\u00e9charger\n<\/a><\/p><\/div>                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-87'>\n<\/style>\n<\/div><\/div><div class=\"ifus-accordion-pagination\" data-total-pages=\"3\"><div class=\"ifus-page-btn ifus-page-prev controls is-disabled\" aria-disabled=\"true\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/prev.svg\" alt=\"Anterior\"><\/div><button type=\"button\" class=\"ifus-page-number controls is-active\" data-page=\"1\">1<\/button><button type=\"button\" class=\"ifus-page-number controls\" data-page=\"2\">2<\/button><button type=\"button\" class=\"ifus-page-number controls\" data-page=\"3\">3<\/button><div class=\"ifus-page-btn ifus-page-next controls\" aria-disabled=\"false\"><img decoding=\"async\" src=\"https:\/\/ziacom.com\/wp-content\/themes\/hello-elementor-child\/assets\/images\/acordeon\/next.svg\" alt=\"Siguiente\"><\/div><\/div><\/div><div class=\"ifus-accordion-empty\" style=\"display:none;\">No se han encontrado resultados.<\/div><\/div><script>(function(){var root=document.getElementById(\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032\");var searchInput=document.getElementById(\"ifus-accordion-260b30dc-411e-424e-917e-5bcda28df032-search\");if(!root){return;}var prevIconSrc=\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/themes\\\/hello-elementor-child\\\/assets\\\/images\\\/acordeon\\\/prev.svg\";var nextIconSrc=\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/themes\\\/hello-elementor-child\\\/assets\\\/images\\\/acordeon\\\/next.svg\";var titles=Array.prototype.slice.call(root.querySelectorAll(\".elementor-tab-title\"));var items=Array.prototype.slice.call(root.querySelectorAll(\".elementor-accordion-item\"));var perPage=parseInt(root.getAttribute(\"data-items-per-page\"),10)||4;var currentPage=1;var filteredItems=items.slice();var totalPages=Math.max(1,Math.ceil(filteredItems.length\/perPage));var pagination=root.querySelector(\".ifus-accordion-pagination\");var wrapper=root.closest(\".ifus-accordion-wrapper\");var emptyState=wrapper?wrapper.querySelector(\".ifus-accordion-empty\"):null;var activeFilterTerm=\"\";function setIconState(title,isOpen){if(!title){return;}var closedIcon=title.querySelector(\".ifus-accordion-icon-closed\");var openIcon=title.querySelector(\".ifus-accordion-icon-open\");if(closedIcon){closedIcon.style.display=isOpen?\"none\":\"inline-block\";}if(openIcon){openIcon.style.display=isOpen?\"inline-block\":\"none\";}}function closeTitle(title){title.classList.remove(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"false\");setIconState(title,false);var panel=title.nextElementSibling;if(panel){panel.classList.remove(\"elementor-active\");panel.style.display=\"none\";}}function openTitle(title){if(!title){return;}title.classList.add(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"true\");setIconState(title,true);var panel=title.nextElementSibling;if(panel){panel.classList.add(\"elementor-active\");panel.style.display=\"block\";}}function closeAllTitles(){titles.forEach(function(title){closeTitle(title);});}function isItemVisible(item){return item.style.display!==\"none\";}function normalize(text){return (text||\"\").toLowerCase();}function escapeRegExp(text){return text.replace(\/[.*+?^${}()|[\\]\\\\]\/g,\"\\$&\");}function escapeHtml(text){return text.replace(\/&\/g,\"&amp;\").replace(\/<\/g,\"&lt;\").replace(\/>\/g,\"&gt;\").replace(\/\\\"\/g,\"&quot;\").replace(\/\\x27\/g,\"&#39;\");}function setTitleHighlight(item,term){var titleEl=item.querySelector(\".ifus-accordion-title-text\");if(!titleEl){return;}var original=titleEl.getAttribute(\"data-original-title\");if(!original){original=titleEl.textContent||\"\";titleEl.setAttribute(\"data-original-title\",original);}if(!term){titleEl.textContent=original;return;}var safeText=escapeHtml(original);var regex=new RegExp(\"(\"+escapeRegExp(term)+\")\",\"ig\");titleEl.innerHTML=safeText.replace(regex,\"<u>$1<\/u>\");}function createArrowControl(type){var isPrev=type===\"prev\";var div=document.createElement(\"div\");div.className=\"ifus-page-btn ifus-page-\"+type+\" controls\";div.setAttribute(\"role\",\"button\");div.setAttribute(\"tabindex\",\"0\");var disabled=isPrev?currentPage<=1:currentPage>=totalPages;if(disabled){div.classList.add(\"is-disabled\");div.setAttribute(\"aria-disabled\",\"true\");}else{div.setAttribute(\"aria-disabled\",\"false\");}var img=document.createElement(\"img\");img.src=isPrev?prevIconSrc:nextIconSrc;img.alt=isPrev?\"Anterior\":\"Siguiente\";div.appendChild(img);div.addEventListener(\"click\",function(){if(isPrev&&currentPage>1){closeAllTitles();renderPage(currentPage-1);}if(!isPrev&&currentPage<totalPages){closeAllTitles();renderPage(currentPage+1);}});div.addEventListener(\"keydown\",function(e){if(e.key===\"Enter\"||e.key===\" \"){e.preventDefault();div.click();}});return div;}function renderPaginationButtons(){if(!pagination){return;}pagination.innerHTML=\"\";if(totalPages<=1){pagination.style.display=\"none\";return;}pagination.style.display=\"flex\";pagination.appendChild(createArrowControl(\"prev\"));for(var page=1;page<=totalPages;page++){var btn=document.createElement(\"button\");btn.type=\"button\";btn.className=\"ifus-page-number controls\"+(page===currentPage?\" is-active\":\"\");btn.setAttribute(\"data-page\",String(page));btn.textContent=String(page);btn.addEventListener(\"click\",function(e){var target=e.currentTarget;var pageValue=parseInt(target.getAttribute(\"data-page\"),10);if(!isNaN(pageValue)){closeAllTitles();renderPage(pageValue);}});pagination.appendChild(btn);}pagination.appendChild(createArrowControl(\"next\"));}function renderPage(page){currentPage=Math.min(Math.max(page,1),totalPages);var start=(currentPage-1)*perPage;var end=start+perPage;var pageItems=filteredItems.slice(start,end);items.forEach(function(item){item.style.display=\"none\";});pageItems.forEach(function(item){item.style.display=\"block\";if(activeFilterTerm){var title=item.querySelector(\".elementor-tab-title\");openTitle(title);}});if(emptyState){emptyState.style.display=filteredItems.length?\"none\":\"block\";}renderPaginationButtons();}function renderFilteredOpenAll(){items.forEach(function(item){item.style.display=\"none\";});filteredItems.forEach(function(item){item.style.display=\"block\";var title=item.querySelector(\".elementor-tab-title\");openTitle(title);});if(emptyState){emptyState.style.display=filteredItems.length?\"none\":\"block\";}renderPaginationButtons();}function applyFilter(){var term=normalize(searchInput?searchInput.value:\"\").trim();activeFilterTerm=term;filteredItems=items.filter(function(item){var titleTextEl=item.querySelector(\".ifus-accordion-title-text\");var originalText=titleTextEl?(titleTextEl.getAttribute(\"data-original-title\")||titleTextEl.textContent||\"\"):\"\";setTitleHighlight(item,term);return normalize(originalText).indexOf(term)!==-1;});totalPages=Math.max(1,Math.ceil(filteredItems.length\/perPage));closeAllTitles();renderPage(1);}titles.forEach(function(title){setIconState(title,false);title.addEventListener(\"click\",function(e){e.preventDefault();var parentItem=title.closest(\".elementor-accordion-item\");if(parentItem&&!isItemVisible(parentItem)){return;}var current=title.nextElementSibling;var isOpen=title.classList.contains(\"elementor-active\");closeAllTitles();if(!isOpen){title.classList.add(\"elementor-active\");title.setAttribute(\"aria-expanded\",\"true\");setIconState(title,true);if(current){current.classList.add(\"elementor-active\");current.style.display=\"block\";}}});});if(searchInput){searchInput.addEventListener(\"input\",applyFilter);}renderPage(1);})();<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mode d&#8217;emploi Vous pouvez consulter ou t\u00e9l\u00e9charger nos fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS) Instructions de recherche dans le mode d&#8217;emploi : En fonction du syst\u00e8me d&rsquo;implant ou du syst\u00e8me [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-151413","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ifus - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/fr\/ifus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ifus - Ziacom\" \/>\n<meta property=\"og:description\" content=\"Mode d&#8217;emploi Vous pouvez consulter ou t\u00e9l\u00e9charger nos fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS) Instructions de recherche dans le mode d&#8217;emploi : En fonction du syst\u00e8me d&rsquo;implant ou du syst\u00e8me [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/fr\/ifus\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T14:10:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/ifus\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/ifus\\\/\",\"name\":\"Ifus - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-03-26T11:15:13+00:00\",\"dateModified\":\"2026-07-01T14:10:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/ifus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/fr\\\/ifus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/ifus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ifus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ifus - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/fr\/ifus\/","og_locale":"fr_FR","og_type":"article","og_title":"Ifus - Ziacom","og_description":"Mode d&#8217;emploi Vous pouvez consulter ou t\u00e9l\u00e9charger nos fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS) Instructions de recherche dans le mode d&#8217;emploi : En fonction du syst\u00e8me d&rsquo;implant ou du syst\u00e8me [&hellip;]","og_url":"https:\/\/ziacom.com\/fr\/ifus\/","og_site_name":"Ziacom","article_modified_time":"2026-07-01T14:10:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/fr\/ifus\/","url":"https:\/\/ziacom.com\/fr\/ifus\/","name":"Ifus - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/fr\/#website"},"datePublished":"2026-03-26T11:15:13+00:00","dateModified":"2026-07-01T14:10:49+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/fr\/ifus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/fr\/ifus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/fr\/ifus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ifus"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/fr\/#website","url":"https:\/\/ziacom.com\/fr\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/151413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/comments?post=151413"}],"version-history":[{"count":3,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/151413\/revisions"}],"predecessor-version":[{"id":155258,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/pages\/151413\/revisions\/155258"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/media?parent=151413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}