{"id":156349,"date":"2026-02-16T10:19:41","date_gmt":"2026-02-16T09:19:41","guid":{"rendered":"https:\/\/ziacom.com\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/"},"modified":"2026-07-07T09:40:02","modified_gmt":"2026-07-07T07:40:02","slug":"nettoyage-et-desinfection-des-instruments-et-des-boites-3","status":"publish","type":"tribe_events","link":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/","title":{"rendered":"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes"},"content":{"rendered":"<p>Protocoles fond\u00e9s sur des donn\u00e9es scientifiques<br \/>\nIntervenant :<\/p>\n<p>Miriam Gordillo (en collaboration avec GALAXY\u00ae)<\/p>\n<p>D\u00e9tails de l&rsquo;\u00e9v\u00e9nement<br \/>\n\ud83d\udcc5 Date : lundi 11 mai<\/p>\n<p>\ud83d\udd59 Horaires : 11 h 30 \u2013 14 h 00<\/p>\n<p>\ud83d\udccd Lieu : Ziacom Medical SL (2, rue des B\u00fahos, Pinto \u2013 Madrid)<\/p>\n<p>R\u00e9sum\u00e9 de la formation \u00ab<br \/>\n\u00bb Renforcement des protocoles de nettoyage et de d\u00e9sinfection du mat\u00e9riel chirurgical.<\/p>\n<p>L&rsquo;accent est mis sur la s\u00e9curit\u00e9 des patients et du personnel soignant.<\/p>\n<p>Atelier pratique : S\u00e9ance consacr\u00e9e au nettoyage et \u00e0 la d\u00e9sinfection.<\/p>\n<p>Inscription :<br \/>\nVeuillez vous adresser \u00e0 votre responsable commercial r\u00e9gional.<\/p>\n<p>Places : en nombre limit\u00e9.<\/p>\n<p>Organis\u00e9 par : Ziacom Agenda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protocoles fond\u00e9s sur des donn\u00e9es scientifiques Intervenant : Miriam Gordillo (en collaboration avec GALAXY\u00ae) D\u00e9tails de l&rsquo;\u00e9v\u00e9nement \ud83d\udcc5 Date : lundi 11 mai \ud83d\udd59 Horaires : 11 h 30 \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":156278,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[568],"class_list":["post-156349","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-formation","cat_formation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom\" \/>\n<meta property=\"og:description\" content=\"Protocoles fond\u00e9s sur des donn\u00e9es scientifiques Intervenant : Miriam Gordillo (en collaboration avec GALAXY\u00ae) D\u00e9tails de l&rsquo;\u00e9v\u00e9nement \ud83d\udcc5 Date : lundi 11 mai \ud83d\udd59 Horaires : 11 h 30 \u2013 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:40:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/formaciones_ziacom_2026.webp?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"497\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/\",\"name\":\"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/formaciones_ziacom_2026.webp?wsr\",\"datePublished\":\"2026-02-16T09:19:41+00:00\",\"dateModified\":\"2026-07-07T07:40:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/formaciones_ziacom_2026.webp?wsr\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/formaciones_ziacom_2026.webp?wsr\",\"width\":497,\"height\":267},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/actividad\\\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom","og_description":"Protocoles fond\u00e9s sur des donn\u00e9es scientifiques Intervenant : Miriam Gordillo (en collaboration avec GALAXY\u00ae) D\u00e9tails de l&rsquo;\u00e9v\u00e9nement \ud83d\udcc5 Date : lundi 11 mai \ud83d\udd59 Horaires : 11 h 30 \u2013 [&hellip;]","og_url":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/","og_site_name":"Ziacom","article_modified_time":"2026-07-07T07:40:02+00:00","og_image":[{"width":497,"height":267,"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/formaciones_ziacom_2026.webp?wsr","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/","url":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/","name":"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/formaciones_ziacom_2026.webp?wsr","datePublished":"2026-02-16T09:19:41+00:00","dateModified":"2026-07-07T07:40:02+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/formaciones_ziacom_2026.webp?wsr","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/formaciones_ziacom_2026.webp?wsr","width":497,"height":267},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/fr\/actividad\/nettoyage-et-desinfection-des-instruments-et-des-boites-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/ziacom.com\/fr\/agenda\/"},{"@type":"ListItem","position":3,"name":"Nettoyage et d\u00e9sinfection des instruments et des bo\u00eetes"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/fr\/#website","url":"https:\/\/ziacom.com\/fr\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tribe_events\/156349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tribe_events\/156349\/revisions"}],"predecessor-version":[{"id":156350,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tribe_events\/156349\/revisions\/156350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/media\/156278"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/media?parent=156349"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tags?post=156349"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ziacom.com\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=156349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}