{"id":149746,"date":"2025-06-12T13:49:18","date_gmt":"2025-06-12T11:49:18","guid":{"rendered":"https:\/\/ziacom.com\/esg\/"},"modified":"2026-06-08T13:00:31","modified_gmt":"2026-06-08T11:00:31","slug":"esg","status":"publish","type":"page","link":"https:\/\/ziacom.com\/it\/esg\/","title":{"rendered":"ESG"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"149746\" class=\"elementor elementor-149746 elementor-9342\" data-elementor-post-type=\"page\">\n\t\t\t\t<section class=\"elementor-element elementor-element-bca50cb header-intro intro-bottom e-flex e-con-boxed e-con e-parent\" data-id=\"bca50cb\" data-element_type=\"container\" id=\"intro-expansores\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a01ff72 title elementor-widget elementor-widget-heading\" data-id=\"a01ff72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ziacom Group ESG<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56a982d subtitle elementor-widget elementor-widget-heading\" data-id=\"56a982d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ambientale, sociale e di Governance aziendale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-d6f2e82 padding-section e-flex e-con-boxed e-con e-parent\" data-id=\"d6f2e82\" data-element_type=\"container\" id=\"esg\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-54b13e4 e-con-full cont-sm e-flex e-con e-child\" data-id=\"54b13e4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dab8665 elementor-widget elementor-widget-text-editor\" data-id=\"dab8665\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"124\" data-end=\"280\"><strong data-start=\"124\" data-end=\"278\">Il nostro impegno nel promuovere i criteri ESG consiste nell&#8217;implementare iniziative che facciano la differenza, trattandole come priorit\u00e0 strategiche per l&#8217;azienda.<\/strong><\/p><p data-start=\"282\" data-end=\"495\"><strong data-start=\"282\" data-end=\"493\">Ziacom Medical Group ha una tabella di marcia per diventare pi\u00f9 sostenibile, offrendo una solida performance che riflette il suo impegno a collegare l&#8217;attivit\u00e0 dell&#8217;azienda alla sostenibilit\u00e0 globale.<\/strong><\/p><p data-start=\"497\" data-end=\"624\"><strong data-start=\"497\" data-end=\"622\">Vogliamo dare il buon esempio, promuovendo pratiche di sviluppo sostenibile in tutte le nostre aree di attivit\u00e0.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b7de9f e-con-full cont-sm e-flex e-con e-child\" data-id=\"1b7de9f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9bd569 elementor-widget elementor-widget-heading\" data-id=\"c9bd569\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ambiente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cf652 contenido elementor-widget elementor-widget-text-editor\" data-id=\"c6cf652\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6665 aligncenter\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp\" alt=\"\" width=\"800\" height=\"530\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp 800w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2-300x199.webp 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2-768x509.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p><strong>Ziacom Medical Group<\/strong> si distingue per il suo<strong> impegno in materia ambientale<\/strong>, ottimizzando l\u2019uso efficiente delle risorse <strong>per ridurre al minimo gli effetti sull\u2019ambiente<\/strong>. A tal fine, \u00e8 stata avviata una <strong>campagna interna con l\u2019obiettivo di ridurre il consumo di carta e materiale immagazzinato<\/strong>, promuovendo <strong>la digitalizzazione<\/strong> e <strong>il riciclaggio <\/strong>non solo di questo materiale, ma anche di tutti i tipi di rifiuti che possono essere prodotti.<\/p><p>Allo stesso modo, crediamo nell\u2019elevata efficienza energetica fornita <strong>dall\u2019illuminazione a LED<\/strong> e utilizziamo questo sistema in tutte le nostre strutture. Grazie al loro basso consumo energetico, i LED ci aiutano a produrre meno inquinamento ambientale e, grazie a una migliore regolazione della potenza di illuminazione, ci consentono di ridurre l\u2019impatto dell\u2019inquinamento luminoso, che l\u2019ambiente apprezza molto. Si effettuano meno processi produttivi per la loro fabbricazione e hanno una lunga durata.   <\/p><p><strong>Misuriamo e controlliamo l\u2019impronta di carbonio <\/strong>prodotta dalla nostra attivit\u00e0. L\u2019aumento dei livelli di questi gas nell\u2019atmosfera sta causando un cambiamento climatico globale: il suo calcolo consente di ridurre o ottimizzare il consumo energetico e modificare le abitudini di consumo, in modo da ridurre al minimo il suo impatto sul pianeta. <strong>Ziacom Medical Group<\/strong> investe in una flotta di veicoli ECO (con marcatura E) che abbassano i consumi tramite un tipo di fonte energetica che riduce il consumo di carburante e quindi le emissioni inquinanti.  <\/p><p>Sappiamo che c\u2019\u00e8 ancora molto da fare in questo settore, per questo siamo in continuo movimento, alla ricerca di alternative e azioni di miglioramento che ci consentano di essere leader nella sostenibilit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1567984 e-con-full cont-sm e-flex e-con e-child\" data-id=\"1567984\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64099b9 elementor-widget elementor-widget-heading\" data-id=\"64099b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sociale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71f66cf contenido elementor-widget elementor-widget-text-editor\" data-id=\"71f66cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"size-full wp-image-6696 aligncenter\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/socialcompanerosw.webp\" alt=\"\" width=\"800\" height=\"591\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/socialcompanerosw.webp 800w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/socialcompanerosw-300x222.webp 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/socialcompanerosw-768x567.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p>L\u2019obiettivo del nostro lavoro in questo caso \u00e8 il <strong>miglioramento del benessere sociale<\/strong> nel contesto in cui operiamo per ottenere un cambiamento positivo.<\/p><p><strong>Ziacom Medical Group affronta la sfida di ridurre le disuguaglianze, garantire i diritti umani e proteggere la salute e la sicurezza dei lavoratori.<\/strong><\/p><p><strong>I diritti umani<\/strong> sono una colonna portante essenziale <strong>per il miglioramento della dimensione sociale di un\u2019azienda<\/strong>. La creazione di politiche interne e di un protocollo di monitoraggio della conformit\u00e0 sono azioni fondamentali che vengono attuate per migliorare questo aspetto. Valutiamo i nostri fornitori e siamo contrari a qualsiasi tipo di sfruttamento o irregolarit\u00e0 che possano mettere in atto.  <\/p><p><strong>La nostra politica aziendale promuove la diversit\u00e0<\/strong>, <strong>l\u2019uguaglianza e l\u2019inclusione<\/strong>, concetti che fanno parte dei nostri impegni e della strategia aziendale da seguire. Le dinamiche sociali sono complesse e in continua evoluzione, per questo applichiamo una solida strategia d\u2019azione, gestendo e migliorando l\u2019intera area coperta dai fattori sociali in azienda. <\/p><p>Il benessere dei lavoratori e delle lavoratrici <strong>nell\u2019ambiente di lavoro \u00e8 uno dei nostri obiettivi principali<\/strong>. Sviluppare piani di salute, sicurezza e prevenzione dei rischi, oltre al monitoraggio continuo dell\u2019ambiente di lavoro, rappresentano dei compiti fondamentali per <strong>Ziacom Medical Group<\/strong> . Sosteniamo un ambiente di lavoro sicuro e sano. Diamo priorit\u00e0 alla gestione del capitale umano, e vengono attuate azioni continue di fidelizzazione, sviluppo e conciliazione.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3898b4 e-con-full cont-sm e-flex e-con e-child\" data-id=\"a3898b4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03ba246 elementor-widget elementor-widget-heading\" data-id=\"03ba246\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impegno per l'inclusione lavorativa delle persone con disabilit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e026b2c contenido elementor-widget elementor-widget-text-editor\" data-id=\"e026b2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"size-large wp-image-6715 aligncenter\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/ChatGPT-Image-19-may-2025-16_03_37-1024x683.webp\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/ChatGPT-Image-19-may-2025-16_03_37-1024x683.webp 1024w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/ChatGPT-Image-19-may-2025-16_03_37-300x200.webp 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/ChatGPT-Image-19-may-2025-16_03_37-768x512.webp 768w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/ChatGPT-Image-19-may-2025-16_03_37.webp 1536w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p>Noi di Ziacom siamo orgogliosi di far parte dell&#8217;iniziativa volta a promuovere l&#8217;inclusione e la diversit\u00e0 sul posto di lavoro. Grazie al nostro accordo con<strong style=\"font-family: inherit;\"> Smart Top Services<\/strong>, collaboriamo attivamente all&#8217;integrazione delle persone con disabilit\u00e0 sul posto di lavoro. Attraverso questa alleanza, lavoriamo per creare uno spazio inclusivo che promuova le pari opportunit\u00e0 e permetta a tutti i dipendenti di sviluppare il proprio potenziale in un ambiente professionale e accessibile. Questo impegno rientra nella nostra strategia ESG, con l&#8217;obiettivo di contribuire positivamente al benessere sociale e alla costruzione di una societ\u00e0 pi\u00f9 equa e diversificata.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0411934 e-con-full cont-sm e-flex e-con e-child\" data-id=\"0411934\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-297c13a elementor-widget elementor-widget-heading\" data-id=\"297c13a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gobernanza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeff590 contenido elementor-widget elementor-widget-text-editor\" data-id=\"aeff590\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-6\"><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6723 size-full aligncenter\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/grupow.webp\" alt=\"\" width=\"800\" height=\"583\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/grupow.webp 800w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/grupow-300x219.webp 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/grupow-768x560.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"deeper-spacer clearfix\" data-config=\"{\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column wpb_content_element\"><div class=\"wpb_wrapper\"><p>Il <strong>fulcro della nostra attivit\u00e0 quotidiana<\/strong> consiste nello <strong>svilupparla in modo etico e responsabile<\/strong>.<\/p><p><strong>Diamo priorit\u00e0 alla qualit\u00e0, alla sicurezza e alla trasparenza.<\/strong><\/p><p>Disponiamo di un dettagliato <strong>sistema di control management<\/strong>, che include processi e procedure, e ci aiuta a essere pi\u00f9 trasparenti nelle nostre prestazioni. Abbiamo una <strong>struttura organizzativa chiara<\/strong>, con linee di responsabilit\u00e0 definite, trasparenti e coerenti, progettata per garantire il rispetto dei valori etici promossi dalla nostra filosofia aziendale, basata su una politica di Codice di Condotta e un Piano per l\u2019Uguaglianza che promuovono la diversit\u00e0, l\u2019uguaglianza e prassi lavorative eccellenti.  <\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"deeper-spacer clearfix\" data-config=\"{\">L\u2019implementazione di un <strong style=\"font-family: inherit;\">Canale Etico a disposizione di chiunque<\/strong> faccia parte della Societ\u00e0 o a essa collegato, ci fornisce la sicurezza di poter essere informati delle violazioni del nostro Codice di Condotta o dell\u2019esistenza di indizi o prove di reati di qualsiasi tipo, potendo agire di conseguenza, applicando i nostri valori e principi basati sulla conformit\u00e0 normativa, che sanziona i comportamenti inadeguati.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ziacom Group ESG Ambientale, sociale e di Governance aziendale Il nostro impegno nel promuovere i criteri ESG consiste nell&#8217;implementare iniziative che facciano la differenza, trattandole come priorit\u00e0 strategiche per l&#8217;azienda. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-149746","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESG - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/it\/esg\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESG - Ziacom\" \/>\n<meta property=\"og:description\" content=\"Ziacom Group ESG Ambientale, sociale e di Governance aziendale Il nostro impegno nel promuovere i criteri ESG consiste nell&#8217;implementare iniziative che facciano la differenza, trattandole come priorit\u00e0 strategiche per l&#8217;azienda. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/it\/esg\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T11:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/\",\"name\":\"ESG - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/bosque-2.webp\",\"datePublished\":\"2025-06-12T11:49:18+00:00\",\"dateModified\":\"2026-06-08T11:00:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/bosque-2.webp\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/bosque-2.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/esg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/it\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESG - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/it\/esg\/","og_locale":"it_IT","og_type":"article","og_title":"ESG - Ziacom","og_description":"Ziacom Group ESG Ambientale, sociale e di Governance aziendale Il nostro impegno nel promuovere i criteri ESG consiste nell&#8217;implementare iniziative che facciano la differenza, trattandole come priorit\u00e0 strategiche per l&#8217;azienda. [&hellip;]","og_url":"https:\/\/ziacom.com\/it\/esg\/","og_site_name":"Ziacom","article_modified_time":"2026-06-08T11:00:31+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp?wsr","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/it\/esg\/","url":"https:\/\/ziacom.com\/it\/esg\/","name":"ESG - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/it\/esg\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/it\/esg\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp","datePublished":"2025-06-12T11:49:18+00:00","dateModified":"2026-06-08T11:00:31+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/it\/esg\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/it\/esg\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ziacom.com\/it\/esg\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2025\/06\/bosque-2.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/it\/esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/it\/"},{"@type":"ListItem","position":2,"name":"ESG"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/it\/#website","url":"https:\/\/ziacom.com\/it\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/pages\/149746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/comments?post=149746"}],"version-history":[{"count":1,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/pages\/149746\/revisions"}],"predecessor-version":[{"id":149747,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/pages\/149746\/revisions\/149747"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/media?parent=149746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}