{"id":156612,"date":"2022-09-28T14:38:23","date_gmt":"2022-09-28T12:38:23","guid":{"rendered":"https:\/\/ziacom.com\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/"},"modified":"2026-07-07T10:15:18","modified_gmt":"2026-07-07T08:15:18","slug":"31-congresso-dellomd-ordine-dei-dentisti-lisbona","status":"publish","type":"tribe_events","link":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/","title":{"rendered":"31\u00b0 Congresso dell&#8217;OMD (Ordine dei Dentisti) | Lisbona"},"content":{"rendered":"<h2>Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell&#8217;OMD (Ordem dos M\u00e9dicos Dentistas).<\/h2>\n<p>Gli obiettivi principali di questa nuova edizione sono riflettere sulle sfide e sugli obiettivi che l&#8217;OMS ci invita a raggiungere in materia di salute orale nel prossimo decennio, oltre a creare collegamenti tra la salute orale e altre aree mediche e a inquadrarne l&#8217;importanza nel contesto della salute sistemica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell&#8217;OMD (Ordem dos M\u00e9dicos Dentistas). Gli obiettivi principali di questa nuova edizione sono riflettere sulle sfide e sugli obiettivi che l&#8217;OMS ci [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":156615,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[575],"class_list":["post-156612","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-evento","cat_evento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>31\u00b0 Congresso dell&#039;OMD (Ordine dei Dentisti) | Lisbona<\/title>\n<meta name=\"description\" content=\"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell&#039;OMD (Ordem dos M\u00e9dicos Dentistas).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31\u00b0 Congresso dell&#039;OMD (Ordine dei Dentisti) | Lisbona\" \/>\n<meta property=\"og:description\" content=\"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell&#039;OMD (Ordem dos M\u00e9dicos Dentistas).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T08:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2022\/09\/1.webp?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/\",\"name\":\"31\u00b0 Congresso dell'OMD (Ordine dei Dentisti) | Lisbona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1.webp?wsr\",\"datePublished\":\"2022-09-28T12:38:23+00:00\",\"dateModified\":\"2026-07-07T08:15:18+00:00\",\"description\":\"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell'OMD (Ordem dos M\u00e9dicos Dentistas).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1.webp?wsr\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/1.webp?wsr\",\"width\":500,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/actividad\\\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/ziacom.com\\\/it\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"31\u00b0 Congresso dell&#8217;OMD (Ordine dei Dentisti) | Lisbona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/it\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31\u00b0 Congresso dell'OMD (Ordine dei Dentisti) | Lisbona","description":"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell'OMD (Ordem dos M\u00e9dicos Dentistas).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/","og_locale":"it_IT","og_type":"article","og_title":"31\u00b0 Congresso dell'OMD (Ordine dei Dentisti) | Lisbona","og_description":"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell'OMD (Ordem dos M\u00e9dicos Dentistas).","og_url":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/","og_site_name":"Ziacom","article_modified_time":"2026-07-07T08:15:18+00:00","og_image":[{"width":500,"height":269,"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2022\/09\/1.webp?wsr","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/","url":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/","name":"31\u00b0 Congresso dell'OMD (Ordine dei Dentisti) | Lisbona","isPartOf":{"@id":"https:\/\/ziacom.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2022\/09\/1.webp?wsr","datePublished":"2022-09-28T12:38:23+00:00","dateModified":"2026-07-07T08:15:18+00:00","description":"Ziacom Medical parteciper\u00e0 alla XXXI edizione del Congresso dell'OMD (Ordem dos M\u00e9dicos Dentistas).","breadcrumb":{"@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2022\/09\/1.webp?wsr","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2022\/09\/1.webp?wsr","width":500,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/it\/actividad\/31-congresso-dellomd-ordine-dei-dentisti-lisbona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/ziacom.com\/it\/agenda\/"},{"@type":"ListItem","position":3,"name":"31\u00b0 Congresso dell&#8217;OMD (Ordine dei Dentisti) | Lisbona"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/it\/#website","url":"https:\/\/ziacom.com\/it\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tribe_events\/156612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tribe_events\/156612\/revisions"}],"predecessor-version":[{"id":156616,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tribe_events\/156612\/revisions\/156616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/media\/156615"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/media?parent=156612"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tags?post=156612"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ziacom.com\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=156612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}