{"id":148708,"date":"2026-04-01T14:45:47","date_gmt":"2026-04-01T12:45:47","guid":{"rendered":"https:\/\/ziacom.com\/capacidad-productiva\/"},"modified":"2026-06-16T17:17:31","modified_gmt":"2026-06-16T15:17:31","slug":"capacidade-de-producao","status":"publish","type":"page","link":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/","title":{"rendered":"Capacidade de produ\u00e7\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"148708\" class=\"elementor elementor-148708 elementor-11594\" data-elementor-post-type=\"page\">\n\t\t\t\t<section class=\"elementor-element elementor-element-db432d5 header-intro intro-bottom e-flex e-con-boxed e-con e-parent\" data-id=\"db432d5\" data-element_type=\"container\" id=\"intro-expansores\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4602cfe title elementor-widget elementor-widget-heading\" data-id=\"4602cfe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fabricantes<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d37d4ac subtitle elementor-widget elementor-widget-heading\" data-id=\"d37d4ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Processo de produ\u00e7\u00e3o 360\u00ba<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-12717c4 e-flex e-con-boxed e-con e-parent\" data-id=\"12717c4\" data-element_type=\"container\" id=\"intro-fabricantes\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-edb7cbd e-con-full e-flex e-con e-child\" data-id=\"edb7cbd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0933752 e-con-full e-flex e-con e-child\" data-id=\"0933752\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b26c37a elementor-widget elementor-widget-text-editor\" data-id=\"b26c37a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O nosso processo de produ\u00e7\u00e3o 360\u00ba inclui o desenho, o fabrico e a distribui\u00e7\u00e3o dos nossos produtos, o que nos permite manter um controlo total sobre a qualidade e os prazos de entrega.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06ab8ee e-con-full cont-dise\u00f1o e-flex e-con e-child\" data-id=\"06ab8ee\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e576fdb e-con-full e-flex e-con e-child\" data-id=\"e576fdb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7ba7c elementor-widget elementor-widget-image\" data-id=\"7b7ba7c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"209\" height=\"110\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png\" class=\"attachment-large size-large wp-image-149542\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f72870 elementor-widget elementor-widget-heading\" data-id=\"5f72870\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Desenho\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af6cab elementor-widget elementor-widget-text-editor\" data-id=\"7af6cab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Implantes desenhados para se adaptarem a todo o tipo de situa\u00e7\u00f5es cl\u00ednicas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46bcdd1 e-con-full e-flex e-con e-child\" data-id=\"46bcdd1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-091e4c1 elementor-widget elementor-widget-image\" data-id=\"091e4c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"209\" height=\"110\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/favricacion.png\" class=\"attachment-large size-large wp-image-149543\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9ce062 elementor-widget elementor-widget-heading\" data-id=\"b9ce062\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fabrico\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2861f76 elementor-widget elementor-widget-text-editor\" data-id=\"2861f76\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rigorosos padr\u00f5es de qualidade nos processos de fabrico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d395479 e-con-full e-flex e-con e-child\" data-id=\"d395479\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2fe83 elementor-widget elementor-widget-image\" data-id=\"7c2fe83\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"209\" height=\"110\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/distribucion.png\" class=\"attachment-large size-large wp-image-149544\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e0a1c7 elementor-widget elementor-widget-heading\" data-id=\"6e0a1c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Distribui\u00e7\u00e3o<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82d7ad1 elementor-widget elementor-widget-text-editor\" data-id=\"82d7ad1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rigoroso cumprimento dos prazos de entrega.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2d0d56 e-con-full cont-box e-flex e-con e-child\" data-id=\"c2d0d56\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad1e76 elementor-widget elementor-widget-image\" data-id=\"2ad1e76\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"553\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/box.png\" class=\"attachment-large size-large wp-image-148709\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/box.png 386w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/box-209x300.png 209w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0024963 text-centro elementor-widget elementor-widget-text-editor\" data-id=\"0024963\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Controlar todo o processo de produ\u00e7\u00e3o d\u00e1-nos uma flexibilidade \u00fanica para satisfazer as suas expetativas e satisfazer as suas necessidades.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7941eb7 difused-bg e-flex e-con-boxed e-con e-parent\" data-id=\"7941eb7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aef720c e-flex e-con-boxed e-con e-parent\" data-id=\"aef720c\" data-element_type=\"container\" id=\"instalaciones-ziacom\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f16c866 elementor-widget elementor-widget-heading\" data-id=\"f16c866\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instala\u00e7\u00f5es da Ziacom<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed0764d e-con-full e-flex e-con e-child\" data-id=\"ed0764d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-61252f9 e-con-full e-flex e-con e-child\" data-id=\"61252f9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fc0f6d elementor-widget elementor-widget-text-editor\" data-id=\"0fc0f6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gra\u00e7as \u00e0s nossas instala\u00e7\u00f5es avan\u00e7adas, garantimos a m\u00e1xima qualidade com uma \u00e1rea de produ\u00e7\u00e3o de 4.000 m\u00b2 <br\/>com m\u00e1quinas e equipamentos de \u00faltima gera\u00e7\u00e3o. Al\u00e9m disso, dispomos de um laborat\u00f3rio e de uma \u00e1rea de testes recentemente ampliados, de salas limpas e cinzentas. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-969736e e-con-full e-flex e-con e-child\" data-id=\"969736e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea88bf5 img-millon elementor-widget elementor-widget-image\" data-id=\"ea88bf5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"181\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/millon-pt.png\" class=\"attachment-large size-large wp-image-153326\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/millon-pt.png 496w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/millon-pt-300x109.png 300w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61a9d6c e-con-full e-flex e-con e-child\" data-id=\"61a9d6c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9e7b51d e-con-full e-flex e-con e-child\" data-id=\"9e7b51d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0167b58 elementor-widget elementor-widget-text-editor\" data-id=\"0167b58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Investimos na capacidade de produ\u00e7\u00e3o para nos adaptarmos \u00e0 crescente procura dos nossos produtos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce04676 elementor-widget elementor-widget-text-editor\" data-id=\"ce04676\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entendemos o investimento na capacidade de produ\u00e7\u00e3o como uma forma de alcan\u00e7ar a m\u00e1xima otimiza\u00e7\u00e3o dos nossos processos de fabrico e de garantir o fornecimento \u00e0s nossas linhas de distribui\u00e7\u00e3o nacionais e internacionais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfde8f4 e-con-full e-flex e-con e-child\" data-id=\"bfde8f4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12cc695 elementor-widget elementor-widget-image\" data-id=\"12cc695\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"458\" height=\"398\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/imagen2.png\" class=\"attachment-large size-large wp-image-149546\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/imagen2.png 458w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/imagen2-300x261.png 300w\" sizes=\"(max-width: 458px) 100vw, 458px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6290fcf fino perseguimos typer elementor-widget elementor-widget-heading\" data-id=\"6290fcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perseguimos a excel\u00eancia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f8ea0c elementor-widget elementor-widget-image\" data-id=\"8f8ea0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"45\" height=\"56\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diploma.png\" class=\"attachment-large size-large wp-image-149417\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e4628 elementor-widget elementor-widget-text-editor\" data-id=\"d8e4628\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ziacom.com\/pt-pt\/qualidade-e-inovacao\/\">Conhe\u00e7a a qualidade Ziacom<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fabricantes Processo de produ\u00e7\u00e3o 360\u00ba O nosso processo de produ\u00e7\u00e3o 360\u00ba inclui o desenho, o fabrico e a distribui\u00e7\u00e3o dos nossos produtos, o que nos permite manter um controlo total [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-148708","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacidade de produ\u00e7\u00e3o - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacidade de produ\u00e7\u00e3o - Ziacom\" \/>\n<meta property=\"og:description\" content=\"Fabricantes Processo de produ\u00e7\u00e3o 360\u00ba O nosso processo de produ\u00e7\u00e3o 360\u00ba inclui o desenho, o fabrico e a distribui\u00e7\u00e3o dos nossos produtos, o que nos permite manter um controlo total [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T15:17:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"209\" \/>\n\t<meta property=\"og:image:height\" content=\"110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/\",\"name\":\"Capacidade de produ\u00e7\u00e3o - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/diseno.png?wsr\",\"datePublished\":\"2026-04-01T12:45:47+00:00\",\"dateModified\":\"2026-06-16T15:17:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/diseno.png?wsr\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/diseno.png?wsr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/capacidade-de-producao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacidade de produ\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacidade de produ\u00e7\u00e3o - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/","og_locale":"pt_PT","og_type":"article","og_title":"Capacidade de produ\u00e7\u00e3o - Ziacom","og_description":"Fabricantes Processo de produ\u00e7\u00e3o 360\u00ba O nosso processo de produ\u00e7\u00e3o 360\u00ba inclui o desenho, o fabrico e a distribui\u00e7\u00e3o dos nossos produtos, o que nos permite manter um controlo total [&hellip;]","og_url":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/","og_site_name":"Ziacom","article_modified_time":"2026-06-16T15:17:31+00:00","og_image":[{"width":209,"height":110,"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png?wsr","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/","url":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/","name":"Capacidade de produ\u00e7\u00e3o - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png?wsr","datePublished":"2026-04-01T12:45:47+00:00","dateModified":"2026-06-16T15:17:31+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png?wsr","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/diseno.png?wsr"},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/pt-pt\/capacidade-de-producao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Capacidade de produ\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/pt-pt\/#website","url":"https:\/\/ziacom.com\/pt-pt\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/148708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=148708"}],"version-history":[{"count":9,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/148708\/revisions"}],"predecessor-version":[{"id":153467,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/148708\/revisions\/153467"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=148708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}