{"id":150084,"date":"2026-02-06T10:42:06","date_gmt":"2026-02-06T09:42:06","guid":{"rendered":"https:\/\/ziacom.com\/microimplantes-dentarios\/microimplantes-dsq\/"},"modified":"2026-06-22T16:21:50","modified_gmt":"2026-06-22T14:21:50","slug":"dsq","status":"publish","type":"page","link":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/","title":{"rendered":"Microimplantes DSQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"150084\" class=\"elementor elementor-150084 elementor-11564\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f7469 elements-header dsq e-flex e-con-boxed e-con e-parent\" data-id=\"e8f7469\" data-element_type=\"container\" id=\"intro-Zimicsx\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a01a4cd e-con-full e-flex e-con e-child\" data-id=\"a01a4cd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4d5b725 e-con-full cont-logo e-flex elementor-invisible e-con e-child\" data-id=\"4d5b725\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0927bc hidden-elem elementor-widget elementor-widget-heading\" data-id=\"b0927bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Zinic MTX<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7e88f dsq-title-image elementor-widget elementor-widget-image\" data-id=\"ec7e88f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"192\" height=\"84\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png\" class=\"attachment-large size-large wp-image-150116\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8df5232 e-con-full header-box-blue e-flex e-con e-child\" data-id=\"8df5232\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08aef2f elementor-widget elementor-widget-heading\" data-id=\"08aef2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Monoimplante<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdf9869 e-con-full cont-img e-flex e-con e-child\" data-id=\"bdf9869\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bfd047 color elementor-widget elementor-widget-image\" data-id=\"7bfd047\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"281\" height=\"533\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/imagen-intro.png\" class=\"attachment-large size-large wp-image-150113\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/imagen-intro.png 281w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/imagen-intro-158x300.png 158w\" sizes=\"(max-width: 281px) 100vw, 281px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa84f0d e-con-full cont-grey e-flex e-con e-child\" data-id=\"aa84f0d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-44e7e29 e-con-full box-grey e-flex elementor-invisible e-con e-child\" data-id=\"44e7e29\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d716468 elementor-widget elementor-widget-text-editor\" data-id=\"d716468\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fabricados en <br\/><strong>Titanio Grado 5 ELI<br\/><\/strong>(Extra Low Interstitials)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-375bbf8 e-flex e-con-boxed e-con e-parent\" data-id=\"375bbf8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b2ea65 elementor-widget elementor-widget-heading\" data-id=\"7b2ea65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Est\u00e9tica e versatilidade...  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed7dda8 elementor-widget elementor-widget-text-editor\" data-id=\"ed7dda8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Implantes ortod\u00f4nticos concebidos pelo Dr. David Su\u00e1rez Quintanilla em colabora\u00e7\u00e3o com a Ziacom.<\/p><p>Os micro-implantes DSQ s\u00e3o dispositivos de ancoragem tempor\u00e1ria extra-alveolares (DSQST) e intra-alveolares (DSQCR) para tratamento ortod\u00f4ntico, cuja utiliza\u00e7\u00e3o permite movimentos limitados a um ou mais dentes ou um efeito geral na arcada a tratar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e1cc10 e-flex e-con-boxed e-con e-parent\" data-id=\"5e1cc10\" data-element_type=\"container\" id=\"dsq\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-13a7b49 e-con-full e-flex e-con e-child\" data-id=\"13a7b49\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24e89f3 elementor-widget elementor-widget-image\" data-id=\"24e89f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"239\" height=\"73\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/dsq-1.png\" class=\"attachment-large size-large wp-image-150111\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c079a elementor-widget elementor-widget-image\" data-id=\"12c079a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"50\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/dsq-dr.png\" class=\"attachment-large size-large wp-image-150092\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/dsq-dr.png 337w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/dsq-dr-300x45.png 300w\" sizes=\"(max-width: 337px) 100vw, 337px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9fd25 elementor-widget elementor-widget-heading\" data-id=\"ba9fd25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ZONA RETENTIVA\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81ef4cb elementor-widget elementor-widget-text-editor\" data-id=\"81ef4cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>A cabe\u00e7a redonda evita a lacera\u00e7\u00e3o dos tecidos.<\/li><li>Ranhura para fixa\u00e7\u00e3o de acess\u00f3rios ortod\u00f4nticos.<\/li><li>Orif\u00edcio de reten\u00e7\u00e3o de 0,70 mm para a utiliza\u00e7\u00e3o de <br\/>fios e ligaduras.<\/li><li>Colo transmucoso de 1,00 mm ou 2,50 mm.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa69e4e e-con-full title-mandibulas e-flex e-con e-child\" data-id=\"aa69e4e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b408cd elementor-widget elementor-widget-heading\" data-id=\"8b408cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">USO INTRA-ALVEOLAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ebb540 e-con-full cont-cuadrado e-flex e-con e-child\" data-id=\"3ebb540\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a74eaf3 elementor-widget elementor-widget-image\" data-id=\"a74eaf3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"19\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/cuadrado.png\" class=\"attachment-large size-large wp-image-150088\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c402ce9 elementor-widget elementor-widget-heading\" data-id=\"c402ce9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c1REA MAIS FREQUENTE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f266989 elementor-widget elementor-widget-image\" data-id=\"f266989\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"333\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-cr-pt-1024x426.jpg\" class=\"attachment-large size-large wp-image-154622\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-cr-pt-1024x426.jpg 1024w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-cr-pt-300x125.jpg 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-cr-pt-768x320.jpg 768w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-cr-pt.jpg 1360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9411fd2 e-con-full line e-flex e-con e-child\" data-id=\"9411fd2\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f8897f e-con-full e-flex e-con e-child\" data-id=\"1f8897f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d02f27 elementor-widget elementor-widget-image\" data-id=\"2d02f27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"295\" height=\"82\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/dsq-2.png\" class=\"attachment-large size-large wp-image-150091\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8e7a6 elementor-widget elementor-widget-image\" data-id=\"7b8e7a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"233\" height=\"50\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/dsq-st.png\" class=\"attachment-large size-large wp-image-150094\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d9781d elementor-widget elementor-widget-heading\" data-id=\"5d9781d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ZONA RETENTIVA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-124912a elementor-widget elementor-widget-text-editor\" data-id=\"124912a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>A cabe\u00e7a tipo bot\u00e3o evita a lacera\u00e7\u00e3o dos tecidos.<\/li><li>Zona de reten\u00e7\u00e3o para a utiliza\u00e7\u00e3o de acess\u00f3rios ortod\u00f4nticos.<\/li><li>Orif\u00edcio de reten\u00e7\u00e3o de 0,70 mm para a utiliza\u00e7\u00e3o de fios e ligaduras.<\/li><li>Colar transmucoso de 3,00 mm.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6db5d7b e-con-full title-mandibulas e-flex e-con e-child\" data-id=\"6db5d7b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5439f18 elementor-widget elementor-widget-heading\" data-id=\"5439f18\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">USO EXTRA-ALVEOLAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e25265 e-con-full cont-cuadrado e-flex e-con e-child\" data-id=\"3e25265\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb9f81e elementor-widget elementor-widget-image\" data-id=\"fb9f81e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"19\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/cuadrado.png\" class=\"attachment-large size-large wp-image-150088\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bccd640 elementor-widget elementor-widget-heading\" data-id=\"bccd640\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c1REA MAIS FREQUENTE<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2b0bcd elementor-widget elementor-widget-image\" data-id=\"a2b0bcd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"232\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-st-pt-1024x297.jpg\" class=\"attachment-large size-large wp-image-154627\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-st-pt-1024x297.jpg 1024w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-st-pt-300x87.jpg 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-st-pt-768x222.jpg 768w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/dsq-st-pt.jpg 1381w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-717f57a e-flex e-con-boxed e-con e-parent\" data-id=\"717f57a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a08fa8 e-con-full e-flex e-con e-child\" data-id=\"2a08fa8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e4c84ca e-con-full e-flex e-con e-child\" data-id=\"e4c84ca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da59d03 elementor-widget elementor-widget-image\" data-id=\"da59d03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ziacom.com\/pt-pt\/instrumentos-cirurgicos\/caixa-cirurgica-dsq\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"242\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/caja-2.png\" class=\"attachment-large size-large wp-image-150096\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/caja-2.png 380w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/caja-2-300x191.png 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86c082d elementor-widget elementor-widget-text-editor\" data-id=\"86c082d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ziacom.com\/pt-pt\/instrumentos-cirurgicos\/caixa-cirurgica-dsq\/\">DESCOBRE A CAIXA CIR\u00daRGICA<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee5b0fd e-con-full e-flex e-con e-child\" data-id=\"ee5b0fd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-12cd109 e-con-full e-flex e-con e-child\" data-id=\"12cd109\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5204c75 elementor-widget elementor-widget-image\" data-id=\"5204c75\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"58\" height=\"41\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/01\/youtube.png\" class=\"attachment-large size-large wp-image-150340\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2dbaef elementor-widget elementor-widget-heading\" data-id=\"a2dbaef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DSQ em a\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be9182a elementor-widget elementor-widget-video\" data-id=\"be9182a\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/KlUY1Q0Btgc&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2404a4 seccion-fondo dsq-bg-img e-flex e-con-boxed e-con e-parent\" data-id=\"a2404a4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16d012f e-flex e-con-boxed e-con e-parent\" data-id=\"16d012f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1345ab5 e-con-full cont-circulos e-flex e-con e-child\" data-id=\"1345ab5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-af69072 e-con-full circulos e-flex e-con e-child\" data-id=\"af69072\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2e17895 e-con-full e-flex e-con e-child\" data-id=\"2e17895\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd4cca elementor-widget elementor-widget-image\" data-id=\"4cd4cca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"258\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo1.png\" class=\"attachment-large size-large wp-image-150110\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo1.png 257w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo1-150x150.png 150w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d56c88 elementor-widget elementor-widget-text-editor\" data-id=\"5d56c88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Corpo c\u00f3nico com <br\/>espiral auto-roscante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1389c7e e-con-full e-flex e-con e-child\" data-id=\"1389c7e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e4dec7 elementor-widget elementor-widget-image\" data-id=\"0e4dec7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"258\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo2.png\" class=\"attachment-large size-large wp-image-150108\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo2.png 257w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo2-150x150.png 150w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf2fa83 elementor-widget elementor-widget-text-editor\" data-id=\"bf2fa83\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Base hexagonal <br\/>de 2,50 mm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32a484f e-con-full e-flex e-con e-child\" data-id=\"32a484f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0476eae elementor-widget elementor-widget-image\" data-id=\"0476eae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"258\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo3.png\" class=\"attachment-large size-large wp-image-150109\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo3.png 257w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/03\/circulo3-150x150.png 150w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8da042 elementor-widget elementor-widget-text-editor\" data-id=\"a8da042\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ponta <br\/>auto-perfurante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af1e0e2 e-con-full box-bg-blue e-flex e-con e-child\" data-id=\"af1e0e2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3765505 e-con-full e-flex e-con e-child\" data-id=\"3765505\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71afd3c elementor-widget elementor-widget-text-editor\" data-id=\"71afd3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li><a href=\"https:\/\/ziacom.com\/Biblioteca\/pt\/Catalogo-pt-DSQ.pdf\">Cat\u00e1logo DSQ<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7dd5c0c e-con-full e-flex e-con e-child\" data-id=\"7dd5c0c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-040dbc8 elementor-widget elementor-widget-text-editor\" data-id=\"040dbc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li><a href=\"https:\/\/ziacom.com\/pt-pt\/instrumentos-cirurgicos\/caixa-cirurgica-dsq\/\">Caixa cir\u00fargica DSQ<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aad2a83 e-con-full e-flex e-con e-child\" data-id=\"aad2a83\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b38d6a elementor-widget elementor-widget-text-editor\" data-id=\"1b38d6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/ziacom.com\/pt-pt\/ifus\/\">Instru\u00e7\u00f5es de utiliza\u00e7\u00e3o<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-969fad9 padding-section e-flex e-con-boxed e-con e-parent\" data-id=\"969fad9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20a8153 elementor-widget elementor-widget-heading\" data-id=\"20a8153\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Outros produtos:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b180d8 e-con-full cont-productos no-padding e-flex e-con e-child\" data-id=\"4b180d8\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-b087ad0 e-con-full producto e-flex e-con e-child\" data-id=\"b087ad0\" data-element_type=\"container\" href=\"https:\/\/ziacom.com\/pt-pt\/regeneracao-e-expansao\/expansores-osseos\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e9e3e8 product-img elementor-widget elementor-widget-image\" data-id=\"1e9e3e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"290\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/kit-expansores-oseos.jpg\" class=\"attachment-large size-large wp-image-148801\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/kit-expansores-oseos.jpg 290w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/kit-expansores-oseos-150x150.jpg 150w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa7cf78 elementor-widget elementor-widget-text-editor\" data-id=\"aa7cf78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kit de expans\u00e3o do elevador sinusal<br\/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-ede3104 e-con-full producto e-flex e-con e-child\" data-id=\"ede3104\" data-element_type=\"container\" href=\"https:\/\/ziacom.com\/pt-pt\/implantes-de-conexao-de-peca-unica\/zmr-zmrs\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d262ae9 product-img elementor-widget elementor-widget-image\" data-id=\"d262ae9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"290\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/zmr-dark.jpg\" class=\"attachment-large size-large wp-image-150117\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/zmr-dark.jpg 290w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/05\/zmr-dark-150x150.jpg 150w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b56091a elementor-widget elementor-widget-text-editor\" data-id=\"b56091a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ZMR Simplicity <br\/>fez implante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a887b08 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a887b08\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ziacom.com\/pt-pt\/instrumentos-cirurgicos\/caixa-cirurgica-dsq\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1148\" height=\"595\" src=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/caja-quirugica-dsq-pt.jpg\" class=\"attachment-full size-full wp-image-153253\" alt=\"\" srcset=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/caja-quirugica-dsq-pt.jpg 1148w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/caja-quirugica-dsq-pt-300x155.jpg 300w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/caja-quirugica-dsq-pt-1024x531.jpg 1024w, https:\/\/ziacom.com\/wp-content\/uploads\/2026\/06\/caja-quirugica-dsq-pt-768x398.jpg 768w\" sizes=\"(max-width: 1148px) 100vw, 1148px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zinic MTX Monoimplante Fabricados en Titanio Grado 5 ELI(Extra Low Interstitials) Est\u00e9tica e versatilidade&#8230; Implantes ortod\u00f4nticos concebidos pelo Dr. David Su\u00e1rez Quintanilla em colabora\u00e7\u00e3o com a Ziacom. Os micro-implantes DSQ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":150006,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-150084","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microimplantes DSQ - Ziacom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microimplantes DSQ - Ziacom\" \/>\n<meta property=\"og:description\" content=\"Zinic MTX Monoimplante Fabricados en Titanio Grado 5 ELI(Extra Low Interstitials) Est\u00e9tica e versatilidade&#8230; Implantes ortod\u00f4nticos concebidos pelo Dr. David Su\u00e1rez Quintanilla em colabora\u00e7\u00e3o com a Ziacom. Os micro-implantes DSQ [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T14:21:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png?wsr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/\",\"name\":\"Microimplantes DSQ - Ziacom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dsq.png?wsr\",\"datePublished\":\"2026-02-06T09:42:06+00:00\",\"dateModified\":\"2026-06-22T14:21:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dsq.png?wsr\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dsq.png?wsr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/microimplantes-dentarios\\\/dsq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microimplantes dent\u00e1rios\",\"item\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/micro-implants-dentaires\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Microimplantes DSQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microimplantes DSQ - Ziacom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/","og_locale":"pt_PT","og_type":"article","og_title":"Microimplantes DSQ - Ziacom","og_description":"Zinic MTX Monoimplante Fabricados en Titanio Grado 5 ELI(Extra Low Interstitials) Est\u00e9tica e versatilidade&#8230; Implantes ortod\u00f4nticos concebidos pelo Dr. David Su\u00e1rez Quintanilla em colabora\u00e7\u00e3o com a Ziacom. Os micro-implantes DSQ [&hellip;]","og_url":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/","og_site_name":"Ziacom","article_modified_time":"2026-06-22T14:21:50+00:00","og_image":[{"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png?wsr","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/","url":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/","name":"Microimplantes DSQ - Ziacom","isPartOf":{"@id":"https:\/\/ziacom.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png?wsr","datePublished":"2026-02-06T09:42:06+00:00","dateModified":"2026-06-22T14:21:50+00:00","breadcrumb":{"@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png?wsr","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/04\/dsq.png?wsr"},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/pt-pt\/microimplantes-dentarios\/dsq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Microimplantes dent\u00e1rios","item":"https:\/\/ziacom.com\/pt-pt\/micro-implants-dentaires\/"},{"@type":"ListItem","position":3,"name":"Microimplantes DSQ"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/pt-pt\/#website","url":"https:\/\/ziacom.com\/pt-pt\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/150084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=150084"}],"version-history":[{"count":19,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/150084\/revisions"}],"predecessor-version":[{"id":154634,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/150084\/revisions\/154634"}],"up":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/pages\/150006"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=150084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}