{"id":156285,"date":"2026-07-06T17:17:54","date_gmt":"2026-07-06T15:17:54","guid":{"rendered":"https:\/\/ziacom.com\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/"},"modified":"2026-07-07T09:39:12","modified_gmt":"2026-07-07T07:39:12","slug":"masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo","status":"publish","type":"tribe_events","link":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/","title":{"rendered":"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Vigo"},"content":{"rendered":"<p>O Dr. Jes\u00fas Ostos vai ministrar, em colabora\u00e7\u00e3o com a Ziacom, o curso <strong>\u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no <\/strong>dia 8 de fevereiro, nas instala\u00e7\u00f5es da Ziacom, em Madrid.<\/p>\n<h2>Dr. Jes\u00fas Ostos<\/h2>\n<ul>\n<li><b> <\/b><b>Licenciado<\/b> <b>em<\/b> <b>Odontologia<\/b> e <b>Especialista<\/b> <b>em<\/b> <b>Estomatologia<\/b><b> Integral de <\/b><b>Adultos<\/b> pela Universidade Santa Mar\u00eda, na Venezuela.<\/li>\n<li><b> <\/b>Especialista em <b>Implantologia<\/b><b>, CPO <\/b>Uninga, S\u00e3o Paulo, Brasil.<\/li>\n<li><b> <\/b>Cursos de Cirurgia Periodontal\/Tratamento dos tecidos moles e <b>Microscopia<\/b> <b>em<\/b> <b>cirurgia<\/b> <b>pl\u00e1stica<\/b><b> periodontal<\/b>, Col\u00f4mbia.<\/li>\n<li><b> <\/b>Membro ativo da <b>ALAO e <\/b>da <b>Digital Dental Craftsmen.<\/b><\/li>\n<li> <b> Diretor da <\/b><b>Dentimpact<\/b><b>.<\/b><\/li>\n<li><b> <\/b><b>Docente<\/b><b> e <\/b><b>colaborador<\/b> em v\u00e1rias universidades e institui\u00e7\u00f5es.<\/li>\n<li><b> <\/b>Palestrante em <b>mais<\/b><b> de 25 <\/b><b>pa\u00edses<\/b><b>.<\/b><\/li>\n<\/ul>\n<h2><strong>Programa<\/strong><\/h2>\n<ul>\n<li>Apresenta\u00e7\u00e3o e boas-vindas.<\/li>\n<li>Provis\u00f3ria.<\/li>\n<li>Recupera\u00e7\u00e3o de provis\u00f5es individualizadas com pagamento imediato.<\/li>\n<li>Pilares cicatriciais personalizados.<\/li>\n<li>Aperitivo.<\/li>\n<\/ul>\n<h2><strong>Detalhes do curso<\/strong><\/h2>\n<p><strong>Dura\u00e7\u00e3o: Das <\/strong>10h \u00e0s 14h.<\/p>\n<p><strong>Vagas: 30 <\/strong><\/p>\n<p><strong>Local: Vigo <\/strong>&#8211; F\u00e1brica Ziacom.<\/p>\n<p><strong>Inscri\u00e7\u00f5es: Fala <\/strong>com o teu representante comercial.<\/p>\n<p>Para mais informa\u00e7\u00f5es, <a href=\"https:\/\/ziacom.com\/pt-pt\/somos-ziacom\/\" target=\"_blank\" rel=\"noopener\">entra em contacto com o representante comercial da tua zona<\/a> ou escreve para <a href=\"mailto:marketing@ziacom.com\">marketing@ziacom.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dr. Jes\u00fas Ostos vai ministrar, em colabora\u00e7\u00e3o com a Ziacom, o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, nas instala\u00e7\u00f5es da Ziacom, em Madrid. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":156286,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[570],"class_list":["post-156285","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-formacao","cat_formacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid<\/title>\n<meta name=\"description\" content=\"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid\" \/>\n<meta property=\"og:description\" content=\"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ziacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:39:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/\",\"name\":\"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr\",\"datePublished\":\"2026-07-06T15:17:54+00:00\",\"dateModified\":\"2026-07-07T07:39:12+00:00\",\"description\":\"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr\",\"contentUrl\":\"https:\\\/\\\/ziacom.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr\",\"width\":920,\"height\":495},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/actividad\\\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/agenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Vigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/\",\"name\":\"Ziacom\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziacom.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid","description":"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/","og_locale":"pt_PT","og_type":"article","og_title":"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid","og_description":"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.","og_url":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/","og_site_name":"Ziacom","article_modified_time":"2026-07-07T07:39:12+00:00","og_image":[{"width":920,"height":495,"url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/","url":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/","name":"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Madrid","isPartOf":{"@id":"https:\/\/ziacom.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/#primaryimage"},"image":{"@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/#primaryimage"},"thumbnailUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr","datePublished":"2026-07-06T15:17:54+00:00","dateModified":"2026-07-07T07:39:12+00:00","description":"O Dr. Jes\u00fas Ostos vai dar o curso \u00abFabrico de provis\u00f3rios personalizados em implantologia\u00bb no dia 8 de fevereiro, em Madrid.","breadcrumb":{"@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/#primaryimage","url":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr","contentUrl":"https:\/\/ziacom.com\/wp-content\/uploads\/2026\/02\/EVENTOS-WORDPRESS-AGENDA-CURSOS-FORMACIONES-ETC-2.webp?wsr","width":920,"height":495},{"@type":"BreadcrumbList","@id":"https:\/\/ziacom.com\/pt-pt\/actividad\/masterclass-com-o-dr-jesus-ostos-confeccao-de-proteses-provisorias-personalizadas-vigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ziacom.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/ziacom.com\/pt-pt\/agenda\/"},{"@type":"ListItem","position":3,"name":"Masterclass com o Dr. Jes\u00fas Ostos | Confec\u00e7\u00e3o de pr\u00f3teses provis\u00f3rias personalizadas | Vigo"}]},{"@type":"WebSite","@id":"https:\/\/ziacom.com\/pt-pt\/#website","url":"https:\/\/ziacom.com\/pt-pt\/","name":"Ziacom","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziacom.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events\/156285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events\/156285\/revisions"}],"predecessor-version":[{"id":156287,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events\/156285\/revisions\/156287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/media\/156286"}],"wp:attachment":[{"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=156285"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=156285"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ziacom.com\/pt-pt\/wp-json\/wp\/v2\/tribe_events_cat?post=156285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}